{"id":131,"count":6,"description":"","link":"https:\/\/colombiamyway.com\/de\/category\/medellin-de\/","name":"Medellin","slug":"medellin-de","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Medellin Archives - Colombia My Way<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/colombiamyway.com\/de\/category\/medellin-de\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Medellin Archives - Colombia My Way\" \/>\n<meta property=\"og:url\" content=\"https:\/\/colombiamyway.com\/de\/category\/medellin-de\/\" \/>\n<meta property=\"og:site_name\" content=\"Colombia My Way\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/category\\\/medellin-de\\\/\",\"url\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/category\\\/medellin-de\\\/\",\"name\":\"Medellin Archives - Colombia My Way\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/category\\\/medellin-de\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/category\\\/medellin-de\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/startseite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Medellin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/\",\"name\":\"Colombia My Way\",\"description\":\"The Guide for the Independent Traveler\",\"publisher\":{\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/#organization\",\"name\":\"Colombia My Way\",\"url\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/colombiamyway.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Green-Modern-and-Minimalistic-Travel-Typography-Logo-2.png?fit=500%2C500&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/colombiamyway.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Green-Modern-and-Minimalistic-Travel-Typography-Logo-2.png?fit=500%2C500&ssl=1\",\"width\":500,\"height\":500,\"caption\":\"Colombia My Way\"},\"image\":{\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61571407164514\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Medellin Archives - Colombia My Way","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/colombiamyway.com\/de\/category\/medellin-de\/","og_locale":"de_DE","og_type":"article","og_title":"Medellin Archives - Colombia My Way","og_url":"https:\/\/colombiamyway.com\/de\/category\/medellin-de\/","og_site_name":"Colombia My Way","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/colombiamyway.com\/de\/category\/medellin-de\/","url":"https:\/\/colombiamyway.com\/de\/category\/medellin-de\/","name":"Medellin Archives - Colombia My Way","isPartOf":{"@id":"https:\/\/colombiamyway.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/colombiamyway.com\/de\/category\/medellin-de\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/colombiamyway.com\/de\/category\/medellin-de\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/colombiamyway.com\/de\/startseite\/"},{"@type":"ListItem","position":2,"name":"Medellin"}]},{"@type":"WebSite","@id":"https:\/\/colombiamyway.com\/de\/#website","url":"https:\/\/colombiamyway.com\/de\/","name":"Colombia My Way","description":"The Guide for the Independent Traveler","publisher":{"@id":"https:\/\/colombiamyway.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/colombiamyway.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/colombiamyway.com\/de\/#organization","name":"Colombia My Way","url":"https:\/\/colombiamyway.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/colombiamyway.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/colombiamyway.com\/wp-content\/uploads\/2024\/12\/Green-Modern-and-Minimalistic-Travel-Typography-Logo-2.png?fit=500%2C500&ssl=1","contentUrl":"https:\/\/i0.wp.com\/colombiamyway.com\/wp-content\/uploads\/2024\/12\/Green-Modern-and-Minimalistic-Travel-Typography-Logo-2.png?fit=500%2C500&ssl=1","width":500,"height":500,"caption":"Colombia My Way"},"image":{"@id":"https:\/\/colombiamyway.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61571407164514"]}]}},"_links":{"self":[{"href":"https:\/\/colombiamyway.com\/de\/wp-json\/wp\/v2\/categories\/131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/colombiamyway.com\/de\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/colombiamyway.com\/de\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/colombiamyway.com\/de\/wp-json\/wp\/v2\/posts?categories=131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}