{"id":262101,"date":"2024-11-20T22:03:40","date_gmt":"2024-11-21T02:03:40","guid":{"rendered":"https:\/\/colombiamyway.com\/die-besten-restaurants-in-filandia-essen-und-trinken-2\/"},"modified":"2025-09-06T14:12:19","modified_gmt":"2025-09-06T18:12:19","slug":"die-besten-restaurants-in-filandia-essen-und-trinken","status":"publish","type":"post","link":"https:\/\/colombiamyway.com\/de\/die-besten-restaurants-in-filandia-essen-und-trinken\/","title":{"rendered":"Die besten Restaurants in Filandia &#8211; Essen und Trinken"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Header&#8221; _builder_version=&#8221;4.27.4&#8243; background_image=&#8221;https:\/\/naarcolombia.com\/wp-content\/uploads\/2024\/11\/Restaurant_fogon_calidense_filandia_quindio_colombia.jpg&#8221; background_position=&#8221;top_center&#8221; max_width_last_edited=&#8221;off|desktop&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;|0%||0%|false|true&#8221; custom_margin_tablet=&#8221;0%|0%||0%||true&#8221; custom_margin_phone=&#8221;|0%||0%|false|true&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; custom_padding=&#8221;250px||250px|0px|false|false&#8221; bottom_divider_color=&#8221;#EABB3F&#8221; bottom_divider_height=&#8221;20px&#8221; collapsed=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;35px||35px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][lwp_divi_breadcrumbs _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/lwp_divi_breadcrumbs][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Maintenance&#8221; _builder_version=&#8221;4.27.3&#8243; custom_margin=&#8221;0px|0%|0px|0%|false|true&#8221; custom_margin_tablet=&#8221;|0%|0%|0%||true&#8221; custom_margin_phone=&#8221;&#8221; custom_margin_last_edited=&#8221;on|desktop&#8221; custom_padding=&#8221;10px||20px||false|false&#8221; border_color_all=&#8221;#ffd07e&#8221; border_width_right=&#8221;0vw&#8221; border_color_right=&#8221;rgba(0,0,0,0)&#8221; border_color_left=&#8221;#EABB3F&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; custom_margin=&#8221;11px|auto||auto|false|false&#8221; custom_padding=&#8221;||32px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text module_id=&#8221;eten-en-drinken-cartagena&#8221; _builder_version=&#8221;4.27.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Noto Sans|700|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#ffffff&#8221; header_2_font_size=&#8221;48px&#8221; header_2_line_height=&#8221;1.2em&#8221; background_color=&#8221;#1b4242&#8243; text_orientation=&#8221;center&#8221; header_2_font_size_tablet=&#8221;&#8221; header_2_font_size_phone=&#8221;25px&#8221; header_2_font_size_last_edited=&#8221;on|desktop&#8221; header_2_text_shadow_style=&#8221;preset1&#8243; border_radii=&#8221;on|10px|10px|10px|10px&#8221; box_shadow_style=&#8221;preset1&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2 style=\"text-align: center;\">Essen und Trinken in Filandia<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.3&#8243; module_alignment=&#8221;center&#8221; custom_margin=&#8221;|||auto|false|false&#8221; custom_padding=&#8221;46px|||||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;#282828&#8243; text_font_size=&#8221;18px&#8221; text_letter_spacing=&#8221;1px&#8221; min_height=&#8221;202px&#8221; custom_margin=&#8221;-12px||3px|||&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span style=\"font-weight: 400;\">Die Restaurants in Filandia im <a href=\"https:\/\/colombiamyway.com\/de\/ein-fuehrer-durch-das-kolumbianische-kaffeedreieck\/\" target=\"_blank\" rel=\"noopener\"><strong>kolumbianischen Kaffeedreieck<\/strong><\/a>, haben einen sehr guten Ruf. Filandia ist daher als der gastronomische Hotspot des Kaffeedreiecks bekannt. Das ist auch unter Kolumbianern bekannt und sonntags sind die Restaurants sehr gut besucht. Auch an netten Caf\u00e9s f\u00fcr eine gute Tasse Kaffee mangelt es nicht.     <\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/naarcolombia.com\/wp-content\/uploads\/2024\/11\/patio_plaza_filandia_colombia-1-300x225.jpg\" width=\"300\" height=\"225\" alt=\"\" class=\"wp-image-254931 alignnone size-medium\"><\/p>\n<p><span style=\"font-weight: 400;\">Hier finden Sie unsere Tipps f\u00fcr die besten Restaurants in Filandia, Tipps f\u00fcr vegetarische und vegane Restaurants in Filandia, die sch\u00f6nsten Caf\u00e9s und die gem\u00fctlichsten Bars, um einen Drink zu nehmen.<\/span><span style=\"font-weight: 400;\"><\/span><\/p>\n<p><span style=\"font-weight: 400;\"><\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.3&#8243; custom_margin=&#8221;11px|auto||auto||&#8221; custom_padding=&#8221;9px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text module_id=&#8221;eten-en-drinken-cartagena&#8221; _builder_version=&#8221;4.27.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Noto Sans|700|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#ffffff&#8221; header_2_font_size=&#8221;48px&#8221; header_2_line_height=&#8221;1.2em&#8221; background_color=&#8221;#1b4242&#8243; text_orientation=&#8221;center&#8221; header_2_font_size_tablet=&#8221;&#8221; header_2_font_size_phone=&#8221;28px&#8221; header_2_font_size_last_edited=&#8221;on|desktop&#8221; header_2_text_shadow_style=&#8221;preset1&#8243; border_radii=&#8221;on|10px|10px|10px|10px&#8221; box_shadow_style=&#8221;preset1&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2 style=\"text-align: center;\">Unsere Tipps<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.16&#8243; module_alignment=&#8221;center&#8221; custom_margin=&#8221;12px|10%||auto||&#8221; custom_padding=&#8221;35px|||||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_divider color=&#8221;#006ef4&#8243; divider_weight=&#8221;3px&#8221; _builder_version=&#8221;4.16&#8243; max_width=&#8221;100px&#8221; custom_margin=&#8221;||0px|&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_text _builder_version=&#8221;4.27.3&#8243; text_font=&#8221;Montserrat|300|||||||&#8221; text_line_height=&#8221;2em&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;||||||||&#8221; header_2_font_size=&#8221;36px&#8221; header_2_line_height=&#8221;1.4em&#8221; max_width=&#8221;700px&#8221; header_2_font_size_tablet=&#8221;30px&#8221; header_2_font_size_phone=&#8221;24px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><strong><span lang=\"NL\">Traditionelles kolumbianisches Essen<\/span><\/strong><\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;FOGON CALIDENSE&#8221; image=&#8221;https:\/\/naarcolombia.com\/wp-content\/uploads\/2024\/11\/Restaurant_fogon_calidense_filandia_quindio_colombia.jpg&#8221; _builder_version=&#8221;4.27.3&#8243; custom_padding=&#8221;30px|30px|21px|30px|false|false&#8221; border_radii_image=&#8221;on|10px|10px|10px|10px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span style=\"font-weight: 400;\">Carrera 5 #5-25.  <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ein traditionelles kolumbianisches Restaurant in einer Seitenstra\u00dfe des Platzes. F\u00fcr das Mittagessen ist es sehr zu empfehlen. Hier essen Sie k\u00f6stlichen Fisch zu einem guten Preis in einer gem\u00fctlichen Atmosph\u00e4re. Das spezielle Mittagsmen\u00fc mit Fisch (Trucha und Mojarra) wurde mit Krautsalat, Reis und Patac\u00f3n serviert.     <\/span><\/p>\n<p><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/naarcolombia.com\/wp-content\/uploads\/2024\/11\/Restaurant_fogon_calidense_filandia_quindio_colombia_muurschilderingen-225x300.jpg\" width=\"225\" height=\"300\" alt=\"\" class=\"wp-image-254913 alignnone size-medium\"><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Das Men\u00fc umfasste Sancocho (Suppe) und Agua panela (Limonade). Und das alles f\u00fcr nur COP24.000\/$6 pro Person. Die farbenfrohen Wandmalereien rundeten das Erlebnis f\u00fcr uns ab.    <\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;RESTAURANTE JOS\u00c9 FERNANDO&#8221; image=&#8221;https:\/\/naarcolombia.com\/wp-content\/uploads\/2024\/11\/restaurante-jose-fernando_filandia_colombia.jpg&#8221; _builder_version=&#8221;4.27.3&#8243; header_line_height=&#8221;1.2em&#8221; custom_padding=&#8221;30px|30px|30px|30px|false|false&#8221; border_radii_image=&#8221;on|10px|10px|10px|10px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span style=\"font-weight: 400;\">Cra. 5 #7-61  <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Dieses Restaurant befindet sich in einem sch\u00f6nen Kolonialgeb\u00e4ude im Herzen von Filandia, in der N\u00e4he der Kirche auf dem zentralen Platz. Bei Jos\u00e9 Fernando k\u00f6nnen Sie die verschiedenen Geschmacksrichtungen der kolumbianischen K\u00fcche probieren und die Speisen werden sch\u00f6n pr\u00e4sentiert. Das Restaurant erstreckt sich \u00fcber 3 Etagen, mit einem Caf\u00e9 im zweiten Stock f\u00fcr eine gute Tasse Kaffee mit einem leckeren Kuchen. Auf der zweiten Etage gibt es eine Dachterrasse.     <\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;BAK\u00daR\u00da RESTAURANTE&#8221; image=&#8221;https:\/\/naarcolombia.com\/wp-content\/uploads\/2024\/11\/Bakuru-restaurante_Filandia_Colombia.jpg&#8221; _builder_version=&#8221;4.27.3&#8243; header_line_height=&#8221;1.2em&#8221; custom_padding=&#8221;30px|30px|30px|30px|false|false&#8221; border_radii_image=&#8221;on|10px|10px|10px|10px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span style=\"font-weight: 400;\">Comida del Pac\u00edfico Colombiano<\/span><span style=\"font-weight: 400;\"><br \/><\/span><span style=\"font-weight: 400;\">Cra. 6 #5, 38  <\/span><\/p>\n<p><span style=\"font-weight: 400;\"><\/span><span style=\"font-weight: 400;\">Hier werden die Traditionen des kolumbianischen Pazifiks lebendig gehalten. In dieser K\u00fcche spielen Fisch und Meeresfr\u00fcchte eine wichtige Rolle. Eines der Gerichte, die Sie dort probieren k\u00f6nnen, ist Ceviche. Au\u00dferdem k\u00f6nnen Sie verschiedene Getr\u00e4nke mit exotischen Fr\u00fcchten bestellen.     <\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.16&#8243; module_alignment=&#8221;center&#8221; custom_margin=&#8221;-3px|10%||auto||&#8221; custom_padding=&#8221;46px|||||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_divider color=&#8221;#006ef4&#8243; divider_weight=&#8221;3px&#8221; _builder_version=&#8221;4.16&#8243; max_width=&#8221;100px&#8221; custom_margin=&#8221;||0px|&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_text _builder_version=&#8221;4.27.3&#8243; text_font=&#8221;Montserrat|300|||||||&#8221; text_line_height=&#8221;2em&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;||||||||&#8221; header_2_font_size=&#8221;36px&#8221; header_2_line_height=&#8221;1.4em&#8221; max_width=&#8221;700px&#8221; header_2_font_size_tablet=&#8221;30px&#8221; header_2_font_size_phone=&#8221;24px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><strong>Internationale Restaurants<\/strong><\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;HELENA ADENTRO  &#8221; image=&#8221;https:\/\/naarcolombia.com\/wp-content\/uploads\/2024\/11\/helena-adentro_restaurante_filandia_colombia.jpg&#8221; _builder_version=&#8221;4.27.3&#8243; custom_padding=&#8221;30px|30px|30px|30px|false|false&#8221; border_radii_image=&#8221;on|10px|10px|10px|10px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span style=\"font-weight: 400;\">Sie Carrera 9#7-05  <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Wenn Sie Lust auf ein anderes als das traditionelle kolumbianische Essen haben, ist dieses Restaurant<\/span><span style=\"font-weight: 400;\">  unbedingt zu empfehlen. Eine leckere Vorspeise ist der Toast mit Auberginen und karamellisierten Zwiebeln.   <\/span><\/p>\n<p><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/naarcolombia.com\/wp-content\/uploads\/2024\/11\/voorgerecht_helena_adentro_restaurant_filandia_colombia-300x225.jpg\" width=\"300\" height=\"225\" alt=\"\" class=\"wp-image-254909 alignnone size-medium\"><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Es gibt auch mehrere vegetarische Optionen wie den ger\u00e4ucherten Hummus mit Reis mit Mandeln und Gem\u00fcse.  <\/span><span style=\"font-weight: 400;\">Vom Restaurant aus haben Sie einen sch\u00f6nen Blick auf das Tal. Lustiges Detail: Dies war das einzige Restaurant in Filandia und Salento, in dem wir gegessen haben, in dem das Personal Englisch sprach. Das sagt Ihnen bereits, dass dies eines der beliebtesten Restaurants in Filandia unter Reisenden ist.    <\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;TUK TUK&#8221; image=&#8221;https:\/\/naarcolombia.com\/wp-content\/uploads\/2024\/11\/tuktuk_restaurante_pad_thai_filandia_colombia.jpg&#8221; _builder_version=&#8221;4.27.3&#8243; header_line_height=&#8221;1.2em&#8221; custom_padding=&#8221;30px|30px|30px|30px|false|false&#8221; border_radii_image=&#8221;on|10px|10px|10px|10px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span style=\"font-weight: 400;\">Cl 7#8-43 local 3, <\/span><span style=\"font-weight: 400;\">Final de la calle del tiempo detenido<\/span><\/p>\n<p><span style=\"font-weight: 400;\"> <\/span><span style=\"font-weight: 400;\">Dieses thail\u00e4ndische Restaurant befindet sich gegen\u00fcber dem Restaurant Helena Adentro und ist als eines der besseren Restaurants in Filandia bekannt. Neben ber\u00fchmten thail\u00e4ndischen Gerichten wie Pad Thai erhalten Sie hier auch verschiedene vegetarische und vegane Gerichte.   <\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;EL MULADAR DACHGESCHOSS&#8221; image=&#8221;https:\/\/naarcolombia.com\/wp-content\/uploads\/2024\/11\/El-Muladar_rooftop_restaurant_ilandia_Colombia-2.jpg&#8221; _builder_version=&#8221;4.27.3&#8243; header_line_height=&#8221;1.2em&#8221; custom_padding=&#8221;30px|30px|30px|30px|false|false&#8221; border_radii_image=&#8221;on|10px|10px|10px|10px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span style=\"font-weight: 400;\">Calle 6 #7-79.  <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Von diesem Restaurant aus k\u00f6nnen Sie einen Panoramablick auf das Tal genie\u00dfen. Nachts ist dies ein besonders romantisches Erlebnis. Neben kolumbianischen Gerichten bekommen Sie hier auch Pizza und Gerichte wie Pad Thai. Das Restaurant ist auch f\u00fcr einen Cocktail mit Aussicht zu empfehlen. Neben dem Restaurant befindet sich      <\/span><a href=\"https:\/\/www.booking.com\/hotel\/co\/muladar.nl.html?aid=7906433&amp;no_rooms=1&amp;group_adults=2\" target=\"_blank\" rel=\"noopener\"><b>Hotel Muladar Luxus<\/b><\/a><span style=\"font-weight: 400;\">. <\/span> <\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Maintenance&#8221; _builder_version=&#8221;4.27.3&#8243; custom_margin=&#8221;0px|0%|0px|0%|false|true&#8221; custom_margin_tablet=&#8221;|0%|0%|0%||true&#8221; custom_margin_phone=&#8221;&#8221; custom_margin_last_edited=&#8221;on|desktop&#8221; custom_padding=&#8221;19px||34px||false|false&#8221; border_color_all=&#8221;#ffd07e&#8221; border_width_right=&#8221;0vw&#8221; border_color_right=&#8221;rgba(0,0,0,0)&#8221; border_color_left=&#8221;#EABB3F&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#f5f5f5&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_testimonial author=&#8221;ColombiaMyWay&#8221; portrait_url=&#8221;https:\/\/colombiamyway.com\/wp-content\/uploads\/2024\/12\/Green-Modern-and-Minimalistic-Travel-Typography-Logo-2.png&#8221; quote_icon=&#8221;off&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; min_height=&#8221;220px&#8221; custom_margin=&#8221;||9px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong>Tipp f\u00fcr Vegetarier<\/strong><\/p>\n<p><strong>Restaurant Aro Iris cocina creativa<br \/><\/strong>Adresse: Km 1.4 V\u00eda Cruces, Filandia.<\/p>\n<p>Dieses Restaurant mit einer sehr sch\u00f6nen Einrichtung liegt 10 Autominuten von Filandia entfernt.  <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/naarcolombia.com\/wp-content\/uploads\/2024\/11\/Arcoiris_vegetarisch-restaurant_filandia_colombia-1-300x225.jpg\" width=\"300\" height=\"225\" alt=\"\" class=\"wp-image-254968 alignnone size-medium\"><\/p>\n<p>Es gibt kein festes Men\u00fc, denn der Chefkoch kocht t\u00e4glich ein spezielles Men\u00fc mit frischen Produkten. Sie k\u00f6nnen angeben, was Sie nicht m\u00f6gen, und der Koch wird dies ber\u00fccksichtigen. <\/p>\n<p><strong> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/naarcolombia.com\/wp-content\/uploads\/2024\/11\/AroIris_vegetarisch_restaurant_Filandia_colombia-3-300x169.jpg\" width=\"300\" height=\"169\" alt=\"\" class=\"wp-image-254934 alignnone size-medium\"><\/strong><\/p>\n<p>[\/et_pb_testimonial][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.16&#8243; module_alignment=&#8221;center&#8221; custom_margin=&#8221;-3px|10%||auto||&#8221; custom_padding=&#8221;46px|||||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_divider color=&#8221;#006ef4&#8243; divider_weight=&#8221;3px&#8221; _builder_version=&#8221;4.16&#8243; max_width=&#8221;100px&#8221; custom_margin=&#8221;||0px|&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_text _builder_version=&#8221;4.27.3&#8243; text_font=&#8221;Montserrat|300|||||||&#8221; text_line_height=&#8221;2em&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;||||||||&#8221; header_2_font_size=&#8221;36px&#8221; header_2_line_height=&#8221;1.4em&#8221; max_width=&#8221;700px&#8221; header_2_font_size_tablet=&#8221;30px&#8221; header_2_font_size_phone=&#8221;24px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><strong><span lang=\"NL\">Kaffee und Fr\u00fchst\u00fcck<\/span><\/strong><\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.3&#8243; module_alignment=&#8221;center&#8221; custom_margin=&#8221;|||auto|false|false&#8221; custom_padding=&#8221;10px||||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; text_font=&#8221;Noto Sans||||||||&#8221; text_text_color=&#8221;#282828&#8243; text_font_size=&#8221;18px&#8221; text_letter_spacing=&#8221;1px&#8221; min_height=&#8221;64px&#8221; custom_margin=&#8221;-12px|||||&#8221; custom_padding=&#8221;||18px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span style=\"font-weight: 400;\">F\u00fcr Kaffees\u00fcchtige wie uns gibt es nichts Sch\u00f6neres, als durch ein wundersch\u00f6nes Dorf zu schlendern und dabei eine Pause einzulegen, um eine Tasse Kaffee, Geb\u00e4ck oder Kuchen zu probieren. Filandia ist mit seinen vielen gem\u00fctlichen Caf\u00e9s und Kaffeer\u00f6stereien der perfekte Ort daf\u00fcr. <\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/naarcolombia.com\/wp-content\/uploads\/2024\/11\/koffie_cafequindio_filandia_colombia-225x300.jpg\" width=\"225\" height=\"300\" alt=\"\" class=\"wp-image-255145 alignnone size-medium\"><\/p>\n<p><span style=\"font-weight: 400;\">Hier sind unsere Tipps f\u00fcr die besten Orte f\u00fcr eine Tasse Kaffee und\/oder ein Fr\u00fchst\u00fcck in Filandia.  <\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.27.3&#8243; custom_padding=&#8221;24px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;MOCAFE&#8221; image=&#8221;https:\/\/naarcolombia.com\/wp-content\/uploads\/2024\/11\/Mocafe_koffie_Filandia_Colombia.jpg&#8221; _builder_version=&#8221;4.27.3&#8243; custom_padding=&#8221;30px|30px|30px|30px|false|false&#8221; border_radii_image=&#8221;on|10px|10px|10px|10px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span style=\"font-weight: 400;\">Calle del tiempo detenido &#8211; Calle 7 #7-62, <\/span><span style=\"font-weight: 400;\">(in der N\u00e4he des Restaurants Helena Adentro)<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Bei Mocafe werden die Kaffeebohnen im Haus ger\u00f6stet, damit Sie die frischeste Tasse Kaffee genie\u00dfen k\u00f6nnen (und einen tollen Duft!). Sie sind kein Kaffeeliebhaber? Es gibt auch    <\/span><i><span style=\"font-weight: 400;\">Schokolade caliente<\/span><\/i><span style=\"font-weight: 400;\">  und Tee von guter Qualit\u00e4t im Mocafe. Ganz zu schweigen von den k\u00f6stlichen Torten und anderen S\u00fc\u00dfigkeiten! <\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;INC\u00d3GNITO CAF\u00c9 KAFFEER\u00d6STEREI&#8221; image=&#8221;https:\/\/naarcolombia.com\/wp-content\/uploads\/2024\/11\/Incognito_coffee_roasters_koffie_filandia_colombia.jpg&#8221; _builder_version=&#8221;4.27.3&#8243; header_line_height=&#8221;1.2em&#8221; custom_padding=&#8221;30px|30px|30px|30px|false|false&#8221; border_radii_image=&#8221;on|10px|10px|10px|10px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span style=\"font-weight: 400;\">Cl. 7#4-45.  <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ihre Tasse Kaffee kann nach verschiedenen Zubereitungsmethoden gebr\u00fcht werden, wobei verschiedene Filtertypen verwendet werden. Die Baristas informieren Sie gerne \u00fcber die Aromen und die Herkunft der verschiedenen Kaffeebohnen. Sie k\u00f6nnen auch ein sch\u00f6nes Souvenir wie Tassen und andere Kaffee-Attribute mit nach Hause nehmen.    <\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;CLAUDIA CAF\u00c9 BAR&#8221; image=&#8221;https:\/\/naarcolombia.com\/wp-content\/uploads\/2024\/11\/claudia_cafe_bar_filandia_colombia.jpg&#8221; _builder_version=&#8221;4.27.3&#8243; custom_padding=&#8221;30px|30px|30px|30px|false|false&#8221; border_radii_image=&#8221;on|10px|10px|10px|10px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Cl. 6 #5-3  <\/p>\n<p><span style=\"font-weight: 400;\">Wenn Sie eine Tasse Kaffee an einem der ber\u00fchmtesten Orte Filandias trinken m\u00f6chten, sollten Sie die Bar Claudia Caf\u00e9 am zentralen Platz nicht auslassen. In diesem mehr als 50 Jahre alten Caf\u00e9 k\u00f6nnen Sie eine ausgezeichnete Tasse Kaffee aus speziell ausgew\u00e4hlten und handwerklich ger\u00f6steten Kaffeebohnen trinken.   <\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;||25px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;CAF\u00c9 QUIND\u00cdO&#8221; image=&#8221;https:\/\/naarcolombia.com\/wp-content\/uploads\/2024\/11\/cafe-Quindio_koffie_filandia_colombia.jpg&#8221; _builder_version=&#8221;4.27.3&#8243; custom_padding=&#8221;30px|30px|14px|30px|false|false&#8221; border_radii_image=&#8221;on|10px|10px|10px|10px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span style=\"font-weight: 400;\">Cr 7#661<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Einer unserer Favoriten in der kolumbianischen Kaffeeregion. Neben Filandia finden Sie das Caf\u00e9 Quind\u00edo unter anderem auch in Salento, Armenia und am Flughafen von Armenia. Hier k\u00f6nnen Sie nicht nur eine gute Tasse Kaffee trinken, sondern auch einen k\u00f6stlichen Kuchen, Pandebono (kolumbianischer K\u00e4sesnack) oder einen &#8220;Energieball&#8221; aus Erdn\u00fcssen kaufen. Und Sie k\u00f6nnen Kaffee oder Nespresso-Kapseln kaufen, um sie mit nach Hause zu nehmen.     <\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;CAFE KOLIBRI REAL&#8221; image=&#8221;https:\/\/naarcolombia.com\/wp-content\/uploads\/2024\/11\/cafe-en-hotel_kolibrie_filandia_colombia.jpg&#8221; _builder_version=&#8221;4.27.3&#8243; header_line_height=&#8221;1.2em&#8221; custom_padding=&#8221;30px|30px|30px|30px|false|false&#8221; border_radii_image=&#8221;on|10px|10px|10px|10px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span style=\"font-weight: 400;\">Cr 6\/Calle Real, 5-95 an der Ecke, im zweiten Stock<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Dieses Caf\u00e9 befindet sich in dem gleichnamigen Hotel. Wir suchten hier Schutz, als es zu regnen begann und bestellten einen sch\u00f6nen &#8220;vino caliente&#8221;! Das Caf\u00e9 ist niedlich und hat Tische mit Blick auf den Platz. Sie k\u00f6nnen hier auch verschiedene Arten von Kaffee, Eisbechern, Kuchen und Waffeln genie\u00dfen.     <\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;ALL\u00cd NO M\u00c1S&#8221; image=&#8221;https:\/\/naarcolombia.com\/wp-content\/uploads\/2024\/11\/Alli-no-mas_restaurante_filandia_colombia.jpg&#8221; _builder_version=&#8221;4.27.3&#8243; custom_padding=&#8221;30px|30px|30px|30px|false|false&#8221; border_radii_image=&#8221;on|10px|10px|10px|10px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Cra. 6 #6-11  <\/p>\n<p><span style=\"font-weight: 400;\">Dieses Restaurant befindet sich in einem Food Court (Giraldo&#8217;s Plaza), in der N\u00e4he des zentralen Platzes. Dort k\u00f6nnen Sie ein gutes und g\u00fcnstiges Fr\u00fchst\u00fcck mit Arepas, Omeletts oder Pfannkuchen mit frischem Obst zu sich nehmen. Dieses Restaurant ist etwas ganz Besonderes, denn es wird ausschlie\u00dflich von Frauen gef\u00fchrt.    <\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.3&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;14px|auto|31px|auto||&#8221; custom_padding=&#8221;11px||8px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_divider color=&#8221;#0054A3&#8243; divider_weight=&#8221;1px&#8221; _builder_version=&#8221;4.27.3&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||-3px|||&#8221; custom_padding=&#8221;4px||2px|||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#f5f5f5&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_testimonial author=&#8221;ColombiaMyWay&#8221; portrait_url=&#8221;https:\/\/colombiamyway.com\/wp-content\/uploads\/2024\/12\/Green-Modern-and-Minimalistic-Travel-Typography-Logo-2.png&#8221; quote_icon=&#8221;off&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong>Bonus-Tipp<\/strong><\/p>\n<p><b>La Casa de Pandebono<br \/><\/b><span style=\"font-weight: 400;\">Cl 7 #5-2 <\/span> <\/p>\n<p><span style=\"font-weight: 400;\">In dieser B\u00e4ckerei in dem markanten gr\u00fcnen Geb\u00e4ude kauften wir am Abend Sandwiches f\u00fcr unser Fr\u00fchst\u00fcck am n\u00e4chsten Tag.  <\/span><\/p>\n<p><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/naarcolombia.com\/wp-content\/uploads\/2024\/11\/la-casa-del-pandebono_filandia_colombia-300x225.jpg\" width=\"300\" height=\"225\" alt=\"\" class=\"wp-image-254936 alignnone size-medium\"><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Hier k\u00f6nnen Sie bis 22 Uhr frische Croissants, Sandwiches, alle Arten von S\u00fc\u00dfigkeiten, Bonyurt (Joghurt) und nat\u00fcrlich Pandebono&#8217;s (kolumbianische K\u00e4sesandwiches) kaufen. Die B\u00e4ckerei befindet sich gegen\u00fcber dem Caf\u00e9 Quind\u00edo.   <\/span><\/p>\n<p><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/naarcolombia.com\/wp-content\/uploads\/2024\/11\/cafe-quindio_tegenover_casadepandebono_filandia_colombia-300x225.jpg\" width=\"300\" height=\"225\" alt=\"\" class=\"wp-image-254970 alignnone size-medium\"><\/span><\/p>\n<p>[\/et_pb_testimonial][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.3&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;14px|auto|31px|auto||&#8221; custom_padding=&#8221;11px||8px|||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_divider color=&#8221;#0054A3&#8243; divider_weight=&#8221;1px&#8221; _builder_version=&#8221;4.27.3&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||-3px|||&#8221; custom_padding=&#8221;4px||2px|||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.16&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_divider color=&#8221;#006ef4&#8243; divider_weight=&#8221;3px&#8221; _builder_version=&#8221;4.16&#8243; max_width=&#8221;100px&#8221; custom_margin=&#8221;||0px|&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_text _builder_version=&#8221;4.27.3&#8243; text_font=&#8221;Montserrat|300|||||||&#8221; text_line_height=&#8221;2em&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;||||||||&#8221; header_2_font_size=&#8221;36px&#8221; header_2_line_height=&#8221;1.4em&#8221; max_width=&#8221;700px&#8221; header_2_font_size_tablet=&#8221;30px&#8221; header_2_font_size_phone=&#8221;24px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Bars<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;FONDA ASAEL&#8221; image=&#8221;https:\/\/naarcolombia.com\/wp-content\/uploads\/2024\/11\/fonda_asael_filandia_colombia.jpg&#8221; _builder_version=&#8221;4.27.3&#8243; custom_padding=&#8221;30px|30px|14px|30px|false|false&#8221; border_radii_image=&#8221;on|10px|10px|10px|10px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span style=\"font-weight: 400;\">Cl. 7 # 7-19<br \/>Calle del tiempo detenido  <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Die Fonda Don Asael ist ein einzigartiger Ort in Filandia, voll von <\/span><i><span style=\"font-weight: 400;\">Ambiente <\/span><\/i>  <span style=\"font-weight: 400;\">und Geschichte. Hier versammeln sich die Einheimischen, um sich zu unterhalten, Musik zu h\u00f6ren &#8211; die auf Langspielplatten gespielt wird &#8211; und zu tanzen.   <\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;RESTAURANTE BAR LA REMESA&#8221; image=&#8221;https:\/\/naarcolombia.com\/wp-content\/uploads\/2024\/11\/restaurante_la_remesa_filandia_colombia.jpg&#8221; _builder_version=&#8221;4.27.3&#8243; header_line_height=&#8221;1.2em&#8221; custom_padding=&#8221;30px|30px|30px|30px|false|false&#8221; border_radii_image=&#8221;on|10px|10px|10px|10px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span style=\"font-weight: 400;\">Cra. 9 #7-05 piso 2  <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ein sch\u00f6ner Ort f\u00fcr einen sch\u00f6nen Cocktail mit Snacks, w\u00e4hrend Sie die sch\u00f6ne Aussicht genie\u00dfen. Das Restaurant befindet sich neben dem Mirador Encanto.   <\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;PATIO PLAZA&#8221; image=&#8221;https:\/\/naarcolombia.com\/wp-content\/uploads\/2024\/11\/patio_plaza_filandia_colombia-1.jpg&#8221; _builder_version=&#8221;4.27.3&#8243; custom_padding=&#8221;30px|30px|30px|30px|false|false&#8221; border_radii_image=&#8221;on|10px|10px|10px|10px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Carrera 5 # 6-38 Parte interna<\/p>\n<p>Ein gem\u00fctlicher Ort f\u00fcr ein Bier oder einen Cocktail mit einem Burger oder einem Snack.  <\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p><div class=\"et_pb_module lwp_divi_breadcrumbs lwp_divi_breadcrumbs_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"lwp-breadcrumbs\"> <span class=\"before\"><\/span> <span vocab=\"https:\/\/schema.org\/\" typeof=\"BreadcrumbList\"><span property=\"itemListElement\" typeof=\"ListItem\"><a property=\"item\" typeof=\"WebPage\" href=\"https:\/\/colombiamyway.com\/de\/\" class=\"home\"><span property=\"name\">Home<\/span><\/a><meta property=\"position\" content=\"1\"><\/span> <span class=\"separator et-pb-icon\">&#x39;<\/span> <\/span><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>Essen und Trinken in FilandiaDie Restaurants in Filandia im kolumbianischen Kaffeedreieck, haben einen sehr guten Ruf. Filandia ist daher als der gastronomische Hotspot des Kaffeedreiecks bekannt. Das ist auch unter Kolumbianern bekannt und sonntags sind die Restaurants sehr gut besucht. Auch an netten Caf\u00e9s f\u00fcr eine gute Tasse Kaffee mangelt es nicht. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":257276,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[167],"tags":[],"class_list":["post-262101","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-filandia-reisefuhrer"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die besten Restaurants in Filandia - Essen und Trinken - Colombia My Way<\/title>\n<meta name=\"description\" content=\"Dies ist ein F\u00fchrer zu den besten Restaurants in Filandia f\u00fcr jeden Geschmack. Lesen Sie unsere Tipps f\u00fcr die besten Restaurants, Bars und Caf\u00e9s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/colombiamyway.com\/de\/die-besten-restaurants-in-filandia-essen-und-trinken\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die besten Restaurants in Filandia - Essen und Trinken - Colombia My Way\" \/>\n<meta property=\"og:description\" content=\"Dies ist ein F\u00fchrer zu den besten Restaurants in Filandia f\u00fcr jeden Geschmack. Lesen Sie unsere Tipps f\u00fcr die besten Restaurants, Bars und Caf\u00e9s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/colombiamyway.com\/de\/die-besten-restaurants-in-filandia-essen-und-trinken\/\" \/>\n<meta property=\"og:site_name\" content=\"Colombia My Way\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61571407164514\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-21T02:03:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-06T18:12:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/colombiamyway.com\/wp-content\/uploads\/2024\/11\/Restaurant_fogon_calidense_filandia_quindio_colombia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"J\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"J\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"18\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/die-besten-restaurants-in-filandia-essen-und-trinken\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/die-besten-restaurants-in-filandia-essen-und-trinken\\\/\"},\"author\":{\"name\":\"J\",\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/#\\\/schema\\\/person\\\/011d515d7815ef4a06a1d4f782f06711\"},\"headline\":\"Die besten Restaurants in Filandia &#8211; Essen und Trinken\",\"datePublished\":\"2024-11-21T02:03:40+00:00\",\"dateModified\":\"2025-09-06T18:12:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/die-besten-restaurants-in-filandia-essen-und-trinken\\\/\"},\"wordCount\":3534,\"publisher\":{\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/die-besten-restaurants-in-filandia-essen-und-trinken\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/colombiamyway.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Restaurant_fogon_calidense_filandia_quindio_colombia.jpg\",\"articleSection\":[\"Filandia Reisef\u00fchrer\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/die-besten-restaurants-in-filandia-essen-und-trinken\\\/\",\"url\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/die-besten-restaurants-in-filandia-essen-und-trinken\\\/\",\"name\":\"Die besten Restaurants in Filandia - Essen und Trinken - Colombia My Way\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/die-besten-restaurants-in-filandia-essen-und-trinken\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/die-besten-restaurants-in-filandia-essen-und-trinken\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/colombiamyway.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Restaurant_fogon_calidense_filandia_quindio_colombia.jpg\",\"datePublished\":\"2024-11-21T02:03:40+00:00\",\"dateModified\":\"2025-09-06T18:12:19+00:00\",\"description\":\"Dies ist ein F\u00fchrer zu den besten Restaurants in Filandia f\u00fcr jeden Geschmack. Lesen Sie unsere Tipps f\u00fcr die besten Restaurants, Bars und Caf\u00e9s.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/die-besten-restaurants-in-filandia-essen-und-trinken\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/colombiamyway.com\\\/de\\\/die-besten-restaurants-in-filandia-essen-und-trinken\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/die-besten-restaurants-in-filandia-essen-und-trinken\\\/#primaryimage\",\"url\":\"https:\\\/\\\/colombiamyway.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Restaurant_fogon_calidense_filandia_quindio_colombia.jpg\",\"contentUrl\":\"https:\\\/\\\/colombiamyway.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Restaurant_fogon_calidense_filandia_quindio_colombia.jpg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/die-besten-restaurants-in-filandia-essen-und-trinken\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/startseite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die besten Restaurants in Filandia &#8211; Essen und Trinken\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/\",\"name\":\"Colombia My Way\",\"description\":\"The Guide for the Independent Traveler\",\"publisher\":{\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/#organization\",\"name\":\"Colombia My Way\",\"url\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/colombiamyway.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Green-Modern-and-Minimalistic-Travel-Typography-Logo-2.png?fit=500%2C500&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/colombiamyway.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Green-Modern-and-Minimalistic-Travel-Typography-Logo-2.png?fit=500%2C500&ssl=1\",\"width\":500,\"height\":500,\"caption\":\"Colombia My Way\"},\"image\":{\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61571407164514\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/#\\\/schema\\\/person\\\/011d515d7815ef4a06a1d4f782f06711\",\"name\":\"J\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf3b73a22b0de0f97a1211e232e3f892dfb68f20041d088345d383fffd417f9c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf3b73a22b0de0f97a1211e232e3f892dfb68f20041d088345d383fffd417f9c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf3b73a22b0de0f97a1211e232e3f892dfb68f20041d088345d383fffd417f9c?s=96&d=mm&r=g\",\"caption\":\"J\"},\"url\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/author\\\/divisitescuracao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die besten Restaurants in Filandia - Essen und Trinken - Colombia My Way","description":"Dies ist ein F\u00fchrer zu den besten Restaurants in Filandia f\u00fcr jeden Geschmack. Lesen Sie unsere Tipps f\u00fcr die besten Restaurants, Bars und Caf\u00e9s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/colombiamyway.com\/de\/die-besten-restaurants-in-filandia-essen-und-trinken\/","og_locale":"de_DE","og_type":"article","og_title":"Die besten Restaurants in Filandia - Essen und Trinken - Colombia My Way","og_description":"Dies ist ein F\u00fchrer zu den besten Restaurants in Filandia f\u00fcr jeden Geschmack. Lesen Sie unsere Tipps f\u00fcr die besten Restaurants, Bars und Caf\u00e9s.","og_url":"https:\/\/colombiamyway.com\/de\/die-besten-restaurants-in-filandia-essen-und-trinken\/","og_site_name":"Colombia My Way","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61571407164514","article_published_time":"2024-11-21T02:03:40+00:00","article_modified_time":"2025-09-06T18:12:19+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/colombiamyway.com\/wp-content\/uploads\/2024\/11\/Restaurant_fogon_calidense_filandia_quindio_colombia.jpg","type":"image\/jpeg"}],"author":"J","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"J","Gesch\u00e4tzte Lesezeit":"18\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/colombiamyway.com\/de\/die-besten-restaurants-in-filandia-essen-und-trinken\/#article","isPartOf":{"@id":"https:\/\/colombiamyway.com\/de\/die-besten-restaurants-in-filandia-essen-und-trinken\/"},"author":{"name":"J","@id":"https:\/\/colombiamyway.com\/de\/#\/schema\/person\/011d515d7815ef4a06a1d4f782f06711"},"headline":"Die besten Restaurants in Filandia &#8211; Essen und Trinken","datePublished":"2024-11-21T02:03:40+00:00","dateModified":"2025-09-06T18:12:19+00:00","mainEntityOfPage":{"@id":"https:\/\/colombiamyway.com\/de\/die-besten-restaurants-in-filandia-essen-und-trinken\/"},"wordCount":3534,"publisher":{"@id":"https:\/\/colombiamyway.com\/de\/#organization"},"image":{"@id":"https:\/\/colombiamyway.com\/de\/die-besten-restaurants-in-filandia-essen-und-trinken\/#primaryimage"},"thumbnailUrl":"https:\/\/colombiamyway.com\/wp-content\/uploads\/2024\/11\/Restaurant_fogon_calidense_filandia_quindio_colombia.jpg","articleSection":["Filandia Reisef\u00fchrer"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/colombiamyway.com\/de\/die-besten-restaurants-in-filandia-essen-und-trinken\/","url":"https:\/\/colombiamyway.com\/de\/die-besten-restaurants-in-filandia-essen-und-trinken\/","name":"Die besten Restaurants in Filandia - Essen und Trinken - Colombia My Way","isPartOf":{"@id":"https:\/\/colombiamyway.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/colombiamyway.com\/de\/die-besten-restaurants-in-filandia-essen-und-trinken\/#primaryimage"},"image":{"@id":"https:\/\/colombiamyway.com\/de\/die-besten-restaurants-in-filandia-essen-und-trinken\/#primaryimage"},"thumbnailUrl":"https:\/\/colombiamyway.com\/wp-content\/uploads\/2024\/11\/Restaurant_fogon_calidense_filandia_quindio_colombia.jpg","datePublished":"2024-11-21T02:03:40+00:00","dateModified":"2025-09-06T18:12:19+00:00","description":"Dies ist ein F\u00fchrer zu den besten Restaurants in Filandia f\u00fcr jeden Geschmack. Lesen Sie unsere Tipps f\u00fcr die besten Restaurants, Bars und Caf\u00e9s.","breadcrumb":{"@id":"https:\/\/colombiamyway.com\/de\/die-besten-restaurants-in-filandia-essen-und-trinken\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/colombiamyway.com\/de\/die-besten-restaurants-in-filandia-essen-und-trinken\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/colombiamyway.com\/de\/die-besten-restaurants-in-filandia-essen-und-trinken\/#primaryimage","url":"https:\/\/colombiamyway.com\/wp-content\/uploads\/2024\/11\/Restaurant_fogon_calidense_filandia_quindio_colombia.jpg","contentUrl":"https:\/\/colombiamyway.com\/wp-content\/uploads\/2024\/11\/Restaurant_fogon_calidense_filandia_quindio_colombia.jpg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/colombiamyway.com\/de\/die-besten-restaurants-in-filandia-essen-und-trinken\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/colombiamyway.com\/de\/startseite\/"},{"@type":"ListItem","position":2,"name":"Die besten Restaurants in Filandia &#8211; Essen und Trinken"}]},{"@type":"WebSite","@id":"https:\/\/colombiamyway.com\/de\/#website","url":"https:\/\/colombiamyway.com\/de\/","name":"Colombia My Way","description":"The Guide for the Independent Traveler","publisher":{"@id":"https:\/\/colombiamyway.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/colombiamyway.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/colombiamyway.com\/de\/#organization","name":"Colombia My Way","url":"https:\/\/colombiamyway.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/colombiamyway.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/colombiamyway.com\/wp-content\/uploads\/2024\/12\/Green-Modern-and-Minimalistic-Travel-Typography-Logo-2.png?fit=500%2C500&ssl=1","contentUrl":"https:\/\/i0.wp.com\/colombiamyway.com\/wp-content\/uploads\/2024\/12\/Green-Modern-and-Minimalistic-Travel-Typography-Logo-2.png?fit=500%2C500&ssl=1","width":500,"height":500,"caption":"Colombia My Way"},"image":{"@id":"https:\/\/colombiamyway.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61571407164514"]},{"@type":"Person","@id":"https:\/\/colombiamyway.com\/de\/#\/schema\/person\/011d515d7815ef4a06a1d4f782f06711","name":"J","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/bf3b73a22b0de0f97a1211e232e3f892dfb68f20041d088345d383fffd417f9c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bf3b73a22b0de0f97a1211e232e3f892dfb68f20041d088345d383fffd417f9c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bf3b73a22b0de0f97a1211e232e3f892dfb68f20041d088345d383fffd417f9c?s=96&d=mm&r=g","caption":"J"},"url":"https:\/\/colombiamyway.com\/de\/author\/divisitescuracao\/"}]}},"_links":{"self":[{"href":"https:\/\/colombiamyway.com\/de\/wp-json\/wp\/v2\/posts\/262101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/colombiamyway.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/colombiamyway.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/colombiamyway.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/colombiamyway.com\/de\/wp-json\/wp\/v2\/comments?post=262101"}],"version-history":[{"count":8,"href":"https:\/\/colombiamyway.com\/de\/wp-json\/wp\/v2\/posts\/262101\/revisions"}],"predecessor-version":[{"id":269017,"href":"https:\/\/colombiamyway.com\/de\/wp-json\/wp\/v2\/posts\/262101\/revisions\/269017"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/colombiamyway.com\/de\/wp-json\/wp\/v2\/media\/257276"}],"wp:attachment":[{"href":"https:\/\/colombiamyway.com\/de\/wp-json\/wp\/v2\/media?parent=262101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/colombiamyway.com\/de\/wp-json\/wp\/v2\/categories?post=262101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/colombiamyway.com\/de\/wp-json\/wp\/v2\/tags?post=262101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}