{"id":262417,"date":"2022-09-12T20:14:13","date_gmt":"2022-09-13T00:14:13","guid":{"rendered":"https:\/\/colombiamyway.com\/alles-ueber-barichara-2\/"},"modified":"2025-09-06T14:16:53","modified_gmt":"2025-09-06T18:16:53","slug":"alles-ueber-barichara","status":"publish","type":"post","link":"https:\/\/colombiamyway.com\/de\/alles-ueber-barichara\/","title":{"rendered":"Alles \u00fcber Barichara"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Header&#8221; _builder_version=&#8221;4.18.0&#8243; background_image=&#8221;https:\/\/naarcolombia.com\/wp-content\/uploads\/2022\/04\/typisch-straatje-in-Barichara_Colombia-1.jpg&#8221; background_position=&#8221;bottom_center&#8221; width=&#8221;100%&#8221; max_width_last_edited=&#8221;off|desktop&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;-85px|50px||50px|false|true&#8221; custom_margin_tablet=&#8221;0%|0%||0%||true&#8221; custom_margin_phone=&#8221;&#8221; custom_margin_last_edited=&#8221;on|desktop&#8221; custom_padding=&#8221;272px||229px|35px|false|false&#8221; bottom_divider_style=&#8221;wave&#8221; bottom_divider_color=&#8221;#EABB3F&#8221; bottom_divider_height=&#8221;20px&#8221; bottom_divider_arrangement=&#8221;above_content&#8221; border_color_all=&#8221;#ffd07e&#8221; border_width_right=&#8221;0vw&#8221; border_color_right=&#8221;#21468B&#8221; border_color_left=&#8221;#EABB3F&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243; border_color_all=&#8221;#ffd07e&#8221; border_width_right=&#8221;0vw&#8221; border_color_right=&#8221;#21468B&#8221; border_color_left=&#8221;#EABB3F&#8221;][et_pb_fullwidth_post_title meta=&#8221;off&#8221; featured_image=&#8221;off&#8221; admin_label=&#8221;Fullwidth Post Title&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; title_font=&#8221;|600|||||||&#8221; title_text_align=&#8221;center&#8221; title_text_color=&#8221;#FFFFFF&#8221; title_font_size=&#8221;45px&#8221; title_line_height=&#8221;1.2em&#8221; background_color=&#8221;#1b4242&#8243; positioning=&#8221;relative&#8221; custom_padding=&#8221;||20px||false|false&#8221; hover_enabled=&#8221;0&#8243; title_font_size_tablet=&#8221;45px&#8221; title_font_size_phone=&#8221;30px&#8221; title_font_size_last_edited=&#8221;on|desktop&#8221; custom_css_main_element=&#8221;position: relative!important;&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_fullwidth_post_title][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; border_color_all=&#8221;#ffd07e&#8221; border_width_right=&#8221;0vw&#8221; border_color_right=&#8221;#21468B&#8221; border_color_left=&#8221;#EABB3F&#8221; custom_padding=&#8221;39px||38px|||&#8221;][et_pb_row _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][lwp_divi_breadcrumbs _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/lwp_divi_breadcrumbs][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Maintenance&#8221; module_id=&#8221;Wie-kommst-du-nach-Kartagena&#8221; _builder_version=&#8221;4.27.4&#8243; background_enable_image=&#8221;off&#8221; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; module_alignment=&#8221;center&#8221; min_height_tablet=&#8221;646px&#8221; min_height_phone=&#8221;1055px&#8221; min_height_last_edited=&#8221;on|desktop&#8221; height_tablet=&#8221;&#8221; height_phone=&#8221;&#8221; height_last_edited=&#8221;on|phone&#8221; max_height_tablet=&#8221;&#8221; max_height_phone=&#8221;&#8221; max_height_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;0px|0px|0px|0px|false|true&#8221; custom_margin_tablet=&#8221;0px|0%|0%|0%|false|true&#8221; custom_margin_phone=&#8221;||0%||false|true&#8221; custom_margin_last_edited=&#8221;on|desktop&#8221; custom_padding=&#8221;35px||34px||false|false&#8221; hover_enabled=&#8221;0&#8243; border_color_all=&#8221;#ffd07e&#8221; border_width_right=&#8221;0vw&#8221; border_color_right=&#8221;#21468B&#8221; border_color_left=&#8221;#EABB3F&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][et_pb_row _builder_version=&#8221;4.16&#8243; module_alignment=&#8221;center&#8221; custom_margin=&#8221;-3px|10%||auto||&#8221; custom_padding=&#8221;46px||18px|||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_divider color=&#8221;#006ef4&#8243; divider_weight=&#8221;3px&#8221; _builder_version=&#8221;4.16&#8243; max_width=&#8221;100px&#8221; custom_margin=&#8221;||0px|&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_text _builder_version=&#8221;4.16&#8243; text_font=&#8221;Montserrat|300|||||||&#8221; text_line_height=&#8221;2em&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;||||||||&#8221; header_2_font_size=&#8221;36px&#8221; header_2_line_height=&#8221;1.4em&#8221; max_width=&#8221;700px&#8221; header_2_font_size_tablet=&#8221;30px&#8221; header_2_font_size_phone=&#8221;24px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><strong><span lang=\"NL\">\u00dcber Barichara<\/span><\/strong><\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.18.0&#8243; background_enable_color=&#8221;off&#8221; width=&#8221;100%&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;2px|auto||13px|false|false&#8221; custom_padding=&#8221;24px|20px||21px||&#8221; box_shadow_style=&#8221;preset2&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.22.1&#8243; text_font=&#8221;||||||||&#8221; text_line_height=&#8221;1.8em&#8221; ul_font_size=&#8221;16px&#8221; header_4_line_height=&#8221;1.3em&#8221; background_color=&#8221;#f5f5f5&#8243; custom_margin=&#8221;12px|5px|21px|0px|false|false&#8221; custom_padding=&#8221;35px|12px|35px|17px|false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span style=\"font-weight: 400;\">Diese sch\u00f6ne Kolonialstadt liegt 120 km von Bucaramanga entfernt, in der Region Santander. Barichara liegt 1300 Meter \u00fcber dem Meeresspiegel und beheimatet etwa 10.000 Menschen. Die Kulisse ist beeindruckend, in den Bergen, am Rande des Chicamocha Canyons, der auch der &#8220;Grand Canyon&#8221; von Kolumbien genannt wird. San Gil &#8211; Kolumbiens Hotspot f\u00fcr Abenteuersportarten &#8211; ist 20 km entfernt. Das Dorf wurde 1978 zum Kulturerbe ernannt. Mit seinen gepflasterten Stra\u00dfen, h\u00fcbschen H\u00e4usern, Kirchen und Pl\u00e4tzen ist das stimmungsvolle Barichara eine Augenweide. Seine koloniale Architektur inspirierte Filmemacher, wie die Macher des <a href=\"https:\/\/www.youtube.com\/watch?v=CaimKeDcudo\" target=\"_blank\" rel=\"noopener\"><strong>Disney-Film Encanto<\/strong><\/a>der 2022 mit einem Oscar ausgezeichnet wurde.      <\/span><\/p>\n<p><strong>Hier finden Sie alles \u00fcber Barichara, die besten Dinge, die Sie unternehmen k\u00f6nnen, <a href=\"https:\/\/www.booking.com\/searchresults.nl.html?ss=Barichara&amp;ssne=Barichara&amp;ssne_untouched=Barichara&amp;sid=e287f8497638818fe0d5a6a30f13273e&amp;aid=7906433&amp;lang=nl&amp;sb=1&amp;src_elem=sb&amp;src=searchresults&amp;dest_id=-577966&amp;dest_type=city&amp;checkin=2023-09-06&amp;checkout=2023-09-07&amp;group_adults=2&amp;no_rooms=1&amp;group_children=0&amp;sb_travel_purpose=leisure\" target=\"_blank\" rel=\"noopener\">die sch\u00f6nsten Hotels<\/a> und die besten Restaurants.  <\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_column _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; type=&#8221;4_4&#8243;][et_pb_code _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<iframe loading=\"lazy\" id=\"stay22-widget\" width=\"100%\" height=\"428\" src=\"https:\/\/www.stay22.com\/embed\/687560fd7c6517955ed783b5\" frameborder=\"0\"><\/iframe>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Maintenance&#8221; _builder_version=&#8221;4.18.0&#8243; custom_margin=&#8221;0px|0%|0px|0%|false|true&#8221; custom_margin_tablet=&#8221;|0%|0%|0%||true&#8221; custom_margin_phone=&#8221;&#8221; custom_margin_last_edited=&#8221;on|desktop&#8221; custom_padding=&#8221;17px||30px||false|false&#8221; border_color_all=&#8221;#ffd07e&#8221; border_width_right=&#8221;0vw&#8221; border_color_right=&#8221;#21468B&#8221; border_color_left=&#8221;#EABB3F&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; custom_margin=&#8221;27px|auto||auto||&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Noto Sans|700|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#ffffff&#8221; header_2_font_size=&#8221;48px&#8221; header_2_line_height=&#8221;1.2em&#8221; background_color=&#8221;#1b4242&#8243; text_orientation=&#8221;center&#8221; custom_margin=&#8221;||6px|||&#8221; custom_padding=&#8221;25px||16px|||&#8221; hover_enabled=&#8221;0&#8243; header_2_font_size_tablet=&#8221;&#8221; header_2_font_size_phone=&#8221;28px&#8221; header_2_font_size_last_edited=&#8221;on|desktop&#8221; header_2_text_shadow_style=&#8221;preset1&#8243; border_radii=&#8221;on|10px|10px|10px|10px&#8221; box_shadow_style=&#8221;preset1&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h2 style=\"text-align: center;\">Spa\u00dfige Dinge in Barichara zu tun<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.16&#8243; module_alignment=&#8221;center&#8221; custom_margin=&#8221;-3px|10%||auto||&#8221; custom_padding=&#8221;46px|||||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_divider color=&#8221;#006ef4&#8243; divider_weight=&#8221;3px&#8221; _builder_version=&#8221;4.16&#8243; max_width=&#8221;100px&#8221; custom_margin=&#8221;||0px|&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_text _builder_version=&#8221;4.27.4&#8243; text_font=&#8221;Montserrat|300|||||||&#8221; text_line_height=&#8221;2em&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;||||||||&#8221; header_2_font_size=&#8221;36px&#8221; header_2_line_height=&#8221;1.4em&#8221; max_width=&#8221;700px&#8221; custom_padding=&#8221;||35px|||&#8221; header_2_font_size_tablet=&#8221;30px&#8221; header_2_font_size_phone=&#8221;24px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><span lang=\"NL\">Unsere Tipps<\/span><\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||21px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;1. Erkunden Sie die Stra\u00dfen in aller Ruhe&#8221; image=&#8221;https:\/\/naarcolombia.com\/wp-content\/uploads\/2022\/04\/de-straatjes-op-je-gemak-verkennen-in-Barichara_Colombia.jpg&#8221; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; header_line_height=&#8221;1.2em&#8221; min_height=&#8221;671.9px&#8221; custom_padding=&#8221;35px|35px||35px||&#8221; box_shadow_style=&#8221;preset1&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span style=\"font-weight: 400;\">Die bei weitem angenehmste Aktivit\u00e4t ist es, sich einfach Zeit zu nehmen und die (steilen) Stra\u00dfen zu erkunden. Unterwegs k\u00f6nnen Sie sich im Parque de las Artes ein wenig ausruhen, eine der Kirchen bewundern, in einem der vielen Kunsthandwerksl\u00e4den st\u00f6bern und in den guten Restaurants einen Happen essen.   <\/span><\/p>\n<p><span style=\"font-weight: 400;\"><\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;2. Machen Sie die Wanderung von Barichara nach Guane&#8221; image=&#8221;https:\/\/naarcolombia.com\/wp-content\/uploads\/2022\/04\/Koeien-die-het-pad-kruisen-op-de-wandeling-van-Barichara-naar-Guane_Colombia.jpg&#8221; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; header_line_height=&#8221;1.2em&#8221; custom_padding=&#8221;35px|35px||35px||&#8221; box_shadow_style=&#8221;preset1&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span style=\"font-weight: 400;\">In etwa 2 Stunden wandern Sie auf einem 5 km langen alten Wanderweg (meist bergab) mitten durch die Natur. Unterwegs k\u00f6nnen Sie V\u00f6gel und&#8230; kreuzende K\u00fche beobachten! In Guane k\u00f6nnen Sie sich umsehen und einige    <\/span><span style=\"font-weight: 400;\">Essen und Trinken, bevor Sie mit einem Tuk Tuk nach Barichara fahren.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; min_height=&#8221;778.1px&#8221; custom_margin=&#8221;8px|auto||auto||&#8221; custom_padding=&#8221;13px||28px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;3. Genie\u00dfen Sie die Aussicht am Salto del Mico&#8221; image=&#8221;https:\/\/naarcolombia.com\/wp-content\/uploads\/2022\/04\/Een-reiziger-is-aan-het-genieten-van-het-uitzicht-bij-Salto-del-Mico-in-Barichara_Colombia-1.jpg&#8221; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; header_line_height=&#8221;1.2em&#8221; custom_margin=&#8221;5px||||false|false&#8221; custom_padding=&#8221;35px|35px|35px|35px|false|false&#8221; box_shadow_style=&#8221;preset1&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span style=\"font-weight: 400;\">Einer der sch\u00f6nsten Aussichtspunkte in der Region Santander und der Instagram-Hotspot schlechthin. Sie k\u00f6nnen dorthin laufen oder ein Tuk-Tuk nehmen.   <\/span><\/p>\n<p><span style=\"font-weight: 400;\"><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Foto @ Redbus<\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;4. Besuchen Sie einen Workshop&#8221; image=&#8221;https:\/\/naarcolombia.com\/wp-content\/uploads\/2022\/04\/Papier-dat-aan-het-drogen-is-bij-de-Taller-de-Papel-de-Barichara_Colombia.jpg&#8221; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; header_line_height=&#8221;1.2em&#8221; min_height=&#8221;650.9px&#8221; custom_margin=&#8221;15px||||false|false&#8221; custom_padding=&#8221;35px|35px|35px|35px|false|false&#8221; box_shadow_style=&#8221;preset1&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span style=\"font-weight: 400;\">Es gibt zahlreiche Ateliers und Werkst\u00e4tten, in denen Kunsthandwerker und Frauen Ihnen gerne zeigen, wie sie arbeiten.<\/span> <span style=\"font-weight: 400;\">Sie k\u00f6nnen zum Beispiel das <\/span><b><a href=\"https:\/\/www.tallerdepapeldebarichara.com\/\" target=\"_blank\" rel=\"noopener\">Taller de Papel de Barichara<\/a>, <\/b><span style=\"font-weight: 400;\">lernen, wie man Papier aus der &#8220;fique&#8221;-Pflanze herstellt<\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; min_height=&#8221;418.5px&#8221; custom_margin=&#8221;17px|auto|15px|auto|false|false&#8221; custom_padding=&#8221;10px||23px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;5. Buchen Sie eine aktive Tour f\u00fcr Ihren Adrenalinkick&#8221; image=&#8221;https:\/\/naarcolombia.com\/wp-content\/uploads\/2022\/04\/een-duovlucht-maken-boven-de-Chicamocha-vallei_paragliding-in-San-Gil_Colombia.jpeg&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_line_height=&#8221;1.2em&#8221; min_height=&#8221;670.5px&#8221; custom_margin=&#8221;15px||||false|false&#8221; custom_padding=&#8221;36px|35px||35px||&#8221; box_shadow_style=&#8221;preset2&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span style=\"font-weight: 400;\">Fans von Outdoor-Sportarten k\u00f6nnen einen Ausflug zum Mountainbiken buchen, <a href=\"https:\/\/www.viator.com\/nl-NL\/tours\/San-Gil\/Rafting-Rio-Chicamocha-2-3\/d50399-193375P3?pid=P00058130&amp;mcid=42383&amp;medium=link\" target=\"_blank\" rel=\"noopener\"><strong>Rafting<\/strong><\/a>oder <a href=\"https:\/\/www.viator.com\/nl-NL\/tours\/San-Gil\/Parapente-Chicamohca\/d50399-136439P1?pid=P00058130&amp;mcid=42383&amp;medium=link\" target=\"_blank\" rel=\"noopener\"><strong>Gleitschirmfliegen \u00fcber der Chicamocha-Schlucht<\/strong><\/a> buchen . In der Gegend von Barichara k\u00f6nnen Sie auch wunderbar reiten. Besuchen Sie auch die   <\/span>  <a href=\"https:\/\/colombiamyway.com\/de\/alles-ueber-san-gil-kolumbien\/\" target=\"_blank\" rel=\"noopener\"><b> Reisef\u00fchrer San Gil<\/b><\/a><span style=\"font-weight: 400;\"> f\u00fcr weitere Informationen. <\/span> <\/p>\n<p><span style=\"font-weight: 400;\">Foto @ parapente San Gil<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;6. Probieren Sie die lokale K\u00fcche&#8221; image=&#8221;https:\/\/naarcolombia.com\/wp-content\/uploads\/2022\/04\/hormigas_culonas_gefrituurde-mieren-eten-in-Barichara_Colombia.jpg&#8221; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; header_line_height=&#8221;1.2em&#8221; min_height=&#8221;518.9px&#8221; custom_margin=&#8221;15px||5px||false|false&#8221; custom_padding=&#8221;35px|36px|103px|35px||&#8221; box_shadow_style=&#8221;preset1&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><b> <span style=\"font-weight: 400;\">Zu den Spezialit\u00e4ten der Region geh\u00f6ren Cabrito (Zicklein) und die Arepa Santandereana, eine traditionelle Arepa, der Maniok und Schweinefleisch zugef\u00fcgt wird. \u00dcberraschenderweise,   <\/span>gebratene Ameisen<span style=\"font-weight: 400;\">  (hormigas culonas) gelten als die gr\u00f6\u00dfte Delikatesse in Barichara. Die Ameisen werden ger\u00f6stet und gesalzen und dann verpackt. Die &#8220;Saison&#8221; beginnt um Ostern (bis Juni) und besonders in dieser Zeit k\u00f6nnen Sie die Hormigas in vielen Gesch\u00e4ften finden.    <\/span><\/b><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.16&#8243; custom_margin=&#8221;30px||||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text module_id=&#8221;eten-en-drinken-cartagena&#8221; _builder_version=&#8221;4.27.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Noto Sans|700|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#ffffff&#8221; header_2_font_size=&#8221;48px&#8221; header_2_line_height=&#8221;1.2em&#8221; background_color=&#8221;#1b4242&#8243; text_orientation=&#8221;center&#8221; hover_enabled=&#8221;0&#8243; header_2_font_size_tablet=&#8221;&#8221; header_2_font_size_phone=&#8221;28px&#8221; header_2_font_size_last_edited=&#8221;on|desktop&#8221; header_2_text_shadow_style=&#8221;preset1&#8243; border_radii=&#8221;on|10px|10px|10px|10px&#8221; box_shadow_style=&#8221;preset1&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h2 style=\"text-align: center;\">Restaurants in Barichara<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.16&#8243; module_alignment=&#8221;center&#8221; custom_margin=&#8221;-3px|10%||auto||&#8221; custom_padding=&#8221;46px|||||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; text_font=&#8221;Noto Sans||||||||&#8221; text_text_color=&#8221;#282828&#8243; text_font_size=&#8221;18px&#8221; text_letter_spacing=&#8221;1px&#8221; custom_margin=&#8221;-12px|||||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>In Barichara k\u00f6nnen Sie sehr gut essen. F\u00fcr eine so kleine Stadt gibt es eine gro\u00dfe Auswahl an Restaurants. Denken Sie daran, dass zu Beginn der Woche viele Restaurants geschlossen sind.  <\/p>\n<p>[\/et_pb_text][et_pb_divider color=&#8221;#006ef4&#8243; divider_weight=&#8221;3px&#8221; _builder_version=&#8221;4.16&#8243; max_width=&#8221;100px&#8221; custom_margin=&#8221;||0px|&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.16&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;ELVIA Cocina lokal&#8221; image=&#8221;https:\/\/naarcolombia.com\/wp-content\/uploads\/2022\/04\/ELVIA_cocina-local-restaurante.png&#8221; _builder_version=&#8221;4.17.3&#8243; custom_padding=&#8221;30px|30px|30px|30px|false|false&#8221; border_radii_image=&#8221;on|10px|10px|10px|10px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span style=\"font-weight: 400;\">Eines der besten Restaurants in Barichara. Es gibt eine kleine Speisekarte mit frischen Gerichten, die wundersch\u00f6n zubereitet sind. Ein Abendessen im ELVIA ist daher nicht nur schmackhaft, sondern auch ein Fest f\u00fcr das Auge.    <\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;Noa comida ligera&#8221; image=&#8221;https:\/\/naarcolombia.com\/wp-content\/uploads\/2022\/04\/Noa-Comida-ligera-restaurant_Barichara_Colombia.jpeg&#8221; _builder_version=&#8221;4.17.3&#8243; header_line_height=&#8221;1.2em&#8221; custom_padding=&#8221;30px|30px|30px|30px|false|false&#8221; border_radii_image=&#8221;on|10px|10px|10px|10px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span style=\"font-weight: 400;\">Kleines Restaurant, dessen Spezialit\u00e4t <em>Fagottos<\/em> sind, eine Art dickes, gut gef\u00fclltes gegrilltes Sandwich mit allen m\u00f6glichen F\u00fcllungen. Andere Gerichte sind Kibbe und Linsenkroketten.   <\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;Bari comidas&#8221; image=&#8221;https:\/\/naarcolombia.com\/wp-content\/uploads\/2022\/04\/Bari-comidas-Italiaans-restaurant-voor-pizza-en-pasta-1.jpeg&#8221; _builder_version=&#8221;4.17.3&#8243; custom_padding=&#8221;30px|30px|30px|30px|false|false&#8221; border_radii_image=&#8221;on|10px|10px|10px|10px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span style=\"font-weight: 400;\">Ein italienisches Restaurant, das hausgemachte Pasta, Pizza und Burger serviert. Au\u00dferdem gibt es hier leckere frische S\u00e4fte.   <\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.16&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;Shanti Recetas para el alma&#8221; image=&#8221;https:\/\/naarcolombia.com\/wp-content\/uploads\/2022\/04\/Shanti-Recetas-para-el-alma-restaurant_Barichara_Colombia.jpeg&#8221; _builder_version=&#8221;4.17.3&#8243; custom_padding=&#8221;30px|30px|30px|30px|false|false&#8221; border_radii_image=&#8221;on|10px|10px|10px|10px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span style=\"font-weight: 400;\">Kleines Restaurant, in dem die gesunden Gerichte frisch zubereitet werden und das meiste Gem\u00fcse selbst angebaut wird.  <\/span><span style=\"font-weight: 400;\">F\u00fcr Poke Bowls, Salate, Quinoa und Ceviche, unter anderem. Es gibt nur ein paar Tische, also rufen Sie an, um einen Tisch zu reservieren.   <\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;Gringo Mike&#039;s  &#8221; image=&#8221;https:\/\/naarcolombia.com\/wp-content\/uploads\/2022\/04\/een-superhamburger-eten-bij-Gringo-Mikes-in-Barichara_Colombia.jpg&#8221; _builder_version=&#8221;4.17.3&#8243; header_line_height=&#8221;1.2em&#8221; custom_padding=&#8221;30px|30px|30px|30px|false|false&#8221; border_radii_image=&#8221;on|10px|10px|10px|10px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span style=\"font-weight: 400;\">Seit Jahren ein Favorit bei Reisenden. In dem gem\u00fctlichen Restaurant am Parque Principal k\u00f6nnen Sie aus einer amerikanisch-mexikanischen Speisekarte mit Nachos, Riesensandwiches und Burgern w\u00e4hlen.   <\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;Al Fogolar Barichara&#8221; image=&#8221;https:\/\/naarcolombia.com\/wp-content\/uploads\/2022\/04\/Restaurante-el-Fogalar_Barichara_Colombia.jpeg&#8221; _builder_version=&#8221;4.17.3&#8243; custom_padding=&#8221;30px|30px|30px|30px|false|false&#8221; border_radii_image=&#8221;on|10px|10px|10px|10px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span style=\"font-weight: 400;\">Restaurant neben der Kathedrale. Pater <\/span><span style=\"font-weight: 400;\">om Balkon in der 1. Etage k\u00f6nnen Sie den Park \u00fcberblicken. Es wird eine umfangreiche Speisekarte mit italienischen und kolumbianischen Gerichten angeboten. Spareribs und Ziegenfleisch aus dem Holzofen sind die Spezialit\u00e4ten des Hauses.    <\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Gallery&#8221; _builder_version=&#8221;4.27.4&#8243; background_color=&#8221;#1b4242&#8243; custom_padding=&#8221;0px||0px|1px||&#8221; top_divider_height=&#8221;18px&#8221; bottom_divider_color=&#8221;#0c71c3&#8243; bottom_divider_height=&#8221;24px&#8221; hover_enabled=&#8221;0&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; border_color_all=&#8221;#ffd07e&#8221; border_width_right=&#8221;0vw&#8221; border_color_right=&#8221;#21468B&#8221; border_color_left=&#8221;#EABB3F&#8221; sticky_enabled=&#8221;0&#8243;][et_pb_row _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;25px|35px|23px|||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Discover Beatuty Title&#8221; _builder_version=&#8221;4.16&#8243; text_font=&#8221;||||&#8221; text_text_color=&#8221;#1a1a1a&#8221; header_font=&#8221;|700|||||||&#8221; header_text_align=&#8221;left&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;55px&#8221; header_letter_spacing=&#8221;1px&#8221; header_line_height=&#8221;1.2em&#8221; custom_padding=&#8221;23px|||50px|false|false&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;%22fade_in%22&#8243; animation_duration=&#8221;500ms&#8221; animation_intensity_slide=&#8221;10%&#8221; header_font_size_tablet=&#8221;45px&#8221; header_font_size_phone=&#8221;35px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1 style=\"text-align: center;\">Planen Sie Ihre Reise nach Barichara<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|phone&#8221; admin_label=&#8221;Maintenance&#8221; module_id=&#8221;transport-ab-cartagena&#8221; _builder_version=&#8221;4.18.0&#8243; min_height_tablet=&#8221;&#8221; min_height_phone=&#8221;803.9px&#8221; min_height_last_edited=&#8221;on|phone&#8221; height_tablet=&#8221;&#8221; height_phone=&#8221;&#8221; height_last_edited=&#8221;on|phone&#8221; max_height_tablet=&#8221;&#8221; max_height_phone=&#8221;&#8221; max_height_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;0px|0px|0px|0px|false|true&#8221; custom_margin_tablet=&#8221;0px|0%|0%|0%|false|true&#8221; custom_margin_phone=&#8221;0px||0%||false|false&#8221; custom_margin_last_edited=&#8221;on|desktop&#8221; custom_padding=&#8221;0px||40px||false|false&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;5px||1px||false|false&#8221; border_color_all=&#8221;#ffd07e&#8221; border_width_right=&#8221;0vw&#8221; border_color_right=&#8221;#21468B&#8221; border_color_left=&#8221;#EABB3F&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row custom_padding_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.16&#8243; min_height=&#8221;115px&#8221; min_height_tablet=&#8221;&#8221; min_height_phone=&#8221;&#8221; min_height_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;20px|auto||auto|false|false&#8221; custom_padding=&#8221;5px||11px||false|false&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;5px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text module_id=&#8221;hoe-kom-je-er-mompox&#8221; _builder_version=&#8221;4.27.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Noto Sans|700|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#ffffff&#8221; header_2_font_size=&#8221;48px&#8221; header_2_line_height=&#8221;1.2em&#8221; background_color=&#8221;#1b4242&#8243; text_orientation=&#8221;center&#8221; custom_padding=&#8221;22px|||||&#8221; hover_enabled=&#8221;0&#8243; header_2_font_size_tablet=&#8221;&#8221; header_2_font_size_phone=&#8221;25px&#8221; header_2_font_size_last_edited=&#8221;on|desktop&#8221; header_2_text_shadow_style=&#8221;preset1&#8243; border_radii=&#8221;on|10px|10px|10px|10px&#8221; box_shadow_style=&#8221;preset1&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h2 style=\"text-align: center;\">Wie Sie dorthin kommen.<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.18.0&#8243; background_enable_color=&#8221;off&#8221; width=&#8221;90%&#8221; custom_margin=&#8221;||30px||false|false&#8221; custom_margin_tablet=&#8221;&#8221; custom_margin_phone=&#8221;||15px||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; custom_padding=&#8221;35px|16px|30px|16px|false|false&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;||20px||false|false&#8221; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; text_font=&#8221;||||||||&#8221; text_line_height=&#8221;1.8em&#8221; ul_font=&#8221;||||||||&#8221; ul_font_size=&#8221;16px&#8221; ul_line_height=&#8221;2em&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span style=\"font-weight: 400;\">Es gibt keinen Flughafen in Barichara. Der n\u00e4chstgelegene Flughafen ist der internationale Flughafen Palonegro in Bucaramanga.   <\/span><span style=\"font-weight: 400;\">  Von hier aus k\u00f6nnen Sie den Bus nach San Gil nehmen (ca. 3h) und von dort aus den Bus nach Barichara (45 Min.) Schneller geht es mit einem privaten Transfer vom Flughafen.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><\/span><span style=\"font-weight: 400;\">Von Bogot\u00e1 aus k\u00f6nnen Sie mit dem Bus nach <a href=\"https:\/\/colombiamyway.com\/de\/alles-ueber-san-gil-kolumbien\/\" target=\"_blank\" rel=\"noopener\"><strong>San Gil<\/strong> <\/a>(ca. 8 Std.). In San Gil nehmen Sie den Bus nach Barichara (45 Min.). Um die lange Busfahrt zu unterbrechen, k\u00f6nnen Sie einen Zwischenstopp in <a href=\"https:\/\/colombiamyway.com\/de\/villa-de-leyva\/\" target=\"_blank\" rel=\"noopener\"><strong>Villa de Leyva<\/strong><\/a> einlegen .  <\/span><\/p>\n<p><span style=\"font-weight: 400;\"><strong>#GoColombia Tipp<\/strong><br \/>Kombinieren Sie Ihre Reise mit anderen Highlights n\u00f6rdlich von Bogot\u00e1, wie Zipaquir\u00e1, Villa de Leyva und dem Chicamocha Canyon und machen Sie eine 2-w\u00f6chige Rundreise von Bogot\u00e1 nach Bucaramanga. Sehen Sie sich unsere Beispielrouten mit einer   <\/span><a href=\"https:\/\/colombiamyway.com\/de\/routen-in-kolumbien\/\" target=\"_blank\" rel=\"noopener\"><b>Reiseroute von Bogota nach Barichara.  <\/b><\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Maintenance&#8221; module_id=&#8221;beste-zeit-cartagena&#8221; _builder_version=&#8221;4.18.0&#8243; background_enable_image=&#8221;off&#8221; custom_margin=&#8221;0px|0px||0px|false|true&#8221; custom_margin_tablet=&#8221;0px|0%|0%|0%||true&#8221; custom_margin_phone=&#8221;&#8221; custom_margin_last_edited=&#8221;on|desktop&#8221; custom_padding=&#8221;22px||20px||false|false&#8221; border_color_all=&#8221;#ffd07e&#8221; border_width_right=&#8221;0vw&#8221; border_color_right=&#8221;#21468B&#8221; border_color_left=&#8221;#EABB3F&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.18.0&#8243; custom_margin_tablet=&#8221;&#8221; custom_margin_phone=&#8221;||-10px||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text module_id=&#8221;beste-tijd-mompox&#8221; _builder_version=&#8221;4.27.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Noto Sans|700|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#ffffff&#8221; header_2_font_size=&#8221;48px&#8221; header_2_line_height=&#8221;1.2em&#8221; background_color=&#8221;#1b4242&#8243; text_orientation=&#8221;center&#8221; custom_padding=&#8221;22px|||||&#8221; hover_enabled=&#8221;0&#8243; header_2_font_size_tablet=&#8221;&#8221; header_2_font_size_phone=&#8221;28px&#8221; header_2_font_size_last_edited=&#8221;on|desktop&#8221; header_2_text_shadow_style=&#8221;preset1&#8243; border_radii=&#8221;on|10px|10px|10px|10px&#8221; box_shadow_style=&#8221;preset1&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h2 style=\"text-align: center;\">Klima und beste Reisezeit<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.16&#8243; background_enable_color=&#8221;off&#8221; width=&#8221;100%&#8221; custom_margin=&#8221;30px|auto|15px|auto|false|false&#8221; custom_padding=&#8221;16px|32px|35px|30px|false|false&#8221; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.17.3&#8243; text_font=&#8221;||||||||&#8221; text_line_height=&#8221;1.8em&#8221; ul_font=&#8221;|700|||||||&#8221; ul_line_height=&#8221;2em&#8221; custom_margin=&#8221;||49px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<ul>\n<li><span style=\"font-weight: 400;\">Barichara hat ein trockenes und angenehmes Klima und kann das ganze Jahr \u00fcber besucht werden. Die Durchschnittstemperatur liegt zwischen 18\u00b0C und 24\u00b0C. Es kann sich aber auch viel w\u00e4rmer anf\u00fchlen, besonders am Nachmittag. Es kann sehr hei\u00df werden, besonders auf dem Weg von Barichara nach Guane.     <\/span><\/li>\n<li><span style=\"font-weight: 400;\"><\/span><span style=\"font-weight: 400;\">Die trockenste Zeit ist von Dezember bis Februar. In der Zeit um Weihnachten und Silvester, in den Sommerferien (besonders im Juli) und in der Semana Santa (Osterwoche) sind viele kolumbianische Touristen in Barichara. Dann ist es teurer und \u00fcberf\u00fcllt, so dass eine fr\u00fchzeitige Reservierung erforderlich ist.    <\/span><\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/naarcolombia.com\/wp-content\/uploads\/2022\/04\/Klimaat-en-beste-tijd-om-te-gaan-naar-Barichara_Colombia.jpg&#8221; title_text=&#8221;Klima und beste Reisezeit f\u00fcr Barichara_Kolumbien&#8221; force_fullwidth=&#8221;on&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.17.3&#8243; custom_margin=&#8221;0px|||||&#8221; custom_padding=&#8221;|||0px||&#8221; animation_direction=&#8221;bottom&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Maintenance&#8221; module_id=&#8221;wo-holzen-cartagena&#8221; _builder_version=&#8221;4.18.0&#8243; custom_margin=&#8221;|0px||0px|false|true&#8221; custom_margin_tablet=&#8221;|0%|0%|0%||true&#8221; custom_margin_phone=&#8221;&#8221; custom_margin_last_edited=&#8221;on|desktop&#8221; custom_padding=&#8221;22px||29px||false|false&#8221; border_color_all=&#8221;#ffd07e&#8221; border_width_right=&#8221;0vw&#8221; border_color_right=&#8221;#21468B&#8221; border_color_left=&#8221;#EABB3F&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; width=&#8221;100%&#8221; custom_padding=&#8221;21px|18px||17px||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text module_id=&#8221;waar-logeren-mompox&#8221; _builder_version=&#8221;4.27.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Noto Sans|700|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#ffffff&#8221; header_2_font_size=&#8221;48px&#8221; header_2_line_height=&#8221;1.2em&#8221; background_color=&#8221;#1b4242&#8243; text_orientation=&#8221;center&#8221; custom_margin=&#8221;||29px|||&#8221; custom_padding=&#8221;21px|||||&#8221; hover_enabled=&#8221;0&#8243; header_2_font_size_tablet=&#8221;&#8221; header_2_font_size_phone=&#8221;28px&#8221; header_2_font_size_last_edited=&#8221;on|desktop&#8221; header_2_text_shadow_style=&#8221;preset1&#8243; border_radii=&#8221;on|10px|10px|10px|10px&#8221; box_shadow_style=&#8221;preset1&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h2 style=\"text-align: center;\">Wo kann man in Barichara \u00fcbernachten?<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.16&#8243; background_enable_color=&#8221;off&#8221; width=&#8221;100%&#8221; min_height=&#8221;540px&#8221; custom_margin=&#8221;30px|auto|15px|auto|false|false&#8221; custom_padding=&#8221;35px|20px|35px|15px|false|false&#8221; box_shadow_style=&#8221;preset3&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_testimonial portrait_url=&#8221;https:\/\/colombiamyway.com\/wp-content\/uploads\/2024\/12\/Green-Modern-and-Minimalistic-Travel-Typography-Logo-2.png&#8221; quote_icon=&#8221;off&#8221; _builder_version=&#8221;4.27.4&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span style=\"font-weight: 400;\">Es gibt ein paar g\u00fcnstige Unterk\u00fcnfte in Barichara, aber die meisten Hotels liegen in der mittleren oder h\u00f6heren Preisklasse. In San Gil gibt es viele g\u00fcnstige Unterk\u00fcnfte, aber dann fehlt Ihnen nat\u00fcrlich der Charme von Barichara. Um Weihnachten, Silvester, Semana Santa (Osterwoche) und im Juli sind die Preise h\u00f6her.    <\/span><\/p>\n<p><b>#ColombiaMyWay Hoteltipps:<\/b><\/p>\n<p><b>1) Aufenthalt in <\/b><b><a href=\"https:\/\/www.booking.com\/hotel\/co\/posada-de-versalles.en-gb.html?aid=7906433&amp;sid=50fbf16d21071c66d54142ebc0a858d0&amp;age=0;all_sr_blocks=984737707_371094118_4_1_0;checkin=2024-10-18;checkout=2024-10-25;dest_id=9847377;dest_type=hotel;dist=0;group_adults=2;group_children=1;hapos=1;highlighted_blocks=984737707_371094118_4_1_0;hpos=1;matching_block_id=984737707_371094118_4_1_0;no_rooms=1;req_adults=2;req_age=0;req_children=1;room1=A%2CA%2C0;sb_price_type=total;sr_order=popularity;sr_pri_blocks=984737707_371094118_4_1_0__175000000;srepoch=1718064964;srpvid=adbe01e182fc0013;type=total;ucfs=1hotelTmpl\" target=\"_blank\" rel=\"noopener\">Sue\u00f1os de Antonio<\/a><br \/><\/b><span style=\"font-weight: 400;\">Unser Favorit, wegen des tollen Service und des sch\u00f6nen Gartens. Buchen Sie das Superior-Doppelzimmer mit Au\u00dfendusche!   <\/span><\/p>\n<p><span style=\"font-weight: 400;\"> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/naarcolombia.com\/wp-content\/uploads\/2024\/06\/posada-suenos-de-antonio_barichara_colombia-300x200.jpeg\" width=\"300\" height=\"200\" alt=\"\" class=\"wp-image-253572 alignnone size-medium\"><\/span><\/p>\n<p><span style=\"font-weight: 400;\"><strong>2)<\/strong> <strong>Gehen Sie zum Glamping!<\/strong> Zum Beispiel in der stimmungsvollen <a href=\"https:\/\/www.booking.com\/hotel\/co\/serrania-del-viento-barichara.nl.html?aid=7906433&amp;no_rooms=1&amp;group_adults=2\" target=\"_blank\" rel=\"noopener\"><strong>Serrania del Viento, <\/strong><\/a><\/span><span style=\"font-weight: 400;\">etwas au\u00dferhalb von Barichara, wo Sie die Aussicht und die Ruhe genie\u00dfen k\u00f6nnen.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/naarcolombia.com\/wp-content\/uploads\/2024\/06\/glamping_serrania-del-viento_barichara_colombia-300x200.jpeg\" width=\"300\" height=\"200\" alt=\"\" class=\"wp-image-253571 alignnone size-medium\"><\/span><\/p>\n<p><strong>3) <a href=\"https:\/\/www.booking.com\/searchresults.nl.html?label=map_widget_default_click_label&amp;sid=666df36988a9e72c3f030bb48555f1f3&amp;aid=2236786&amp;ss=Barichara+%E2%80%A2+Vakantiehuizen&amp;ssne=Mompos&amp;ssne_untouched=Mompos&amp;highlighted_hotels=4468417&amp;lang=nl&amp;src=searchresults&amp;dest_id=-577966&amp;dest_type=city&amp;order_ht_id=220&amp;ac_position=0&amp;ac_click_type=b&amp;ac_langcode=nl&amp;ac_suggestion_list_length=1&amp;search_selected=true&amp;search_pageview_id=b3b384436c610252&amp;checkin=2022-09-02&amp;checkout=2022-09-05&amp;group_adults=2&amp;no_rooms=1&amp;group_children=0&amp;sb_travel_purpose=leisure&amp;nflt=ht_id%3D220\" target=\"_blank\" rel=\"noopener\">Buchen Sie ein Ferienhaus<\/a><br \/><\/strong><strong><span style=\"font-weight: 400;\">In Barichara gibt es sehr sch\u00f6ne H\u00e4user zu mieten, wie zum Beispiel <a href=\"https:\/\/www.booking.com\/hotel\/co\/casa-el-paraiso.en-gb.html?aid=2236786&amp;label=map_widget_default_click_label&amp;sid=50fbf16d21071c66d54142ebc0a858d0&amp;age=0;checkin=2022-09-02;checkout=2022-09-05;dcs_click=1;dest_id=-577966;dest_type=city;dist=0;group_adults=2;group_children=0;hapos=1;hpos=1;nflt=ht_id%3D220;no_rooms=1;req_adults=2;req_children=0;room1=A%2CA;sb_price_type=total;sr_order=popularity;srepoch=1718065961;srpvid=dabe039af7d8012c;type=total;ucfs=1hotelTmpl\" target=\"_blank\" rel=\"noopener\"><strong>Casa el Para\u00edso.<\/strong><\/a> Wenn Sie mit Ihrer Familie oder mit Freunden unterwegs sind, sind die Kosten oft nicht allzu hoch. Die meisten H\u00e4user haben eine private Terrasse mit Aussicht und einige sogar einen privaten Pool oder Jacuzzi. Je nach Luxus und Anzahl der Schlafzimmer k\u00f6nnen Sie ein Ferienhaus mit 2 Schlafzimmern schon ab 80 Dollar pro Nacht buchen.    <\/span><\/strong><\/p>\n<p><strong><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/naarcolombia.com\/wp-content\/uploads\/2024\/06\/Casa-el-Paraiso_vakantiehuis_Barichara_Colombia-300x200.jpeg\" width=\"300\" height=\"200\" alt=\"\" class=\"wp-image-253573 alignnone size-medium\"><\/span><\/strong><\/p>\n<p><b>3) Und wenn Sie etwas ganz Besonderes wollen.<br \/><\/b><span style=\"font-weight: 400;\">Dann buchen Sie ein Zimmer im <a href=\"https:\/\/www.booking.com\/hotel\/co\/mahanaim-hostal.nl.html?aid=7906433&amp;no_rooms=1&amp;group_adults=2\" target=\"_blank\" rel=\"noopener\"><strong>Casa Mahanaim<\/strong><\/a>, 2 km von Barichara entfernt. Die Einrichtung und die Lage inmitten der Natur machen diese Casa zu etwas ganz Besonderem. Es gibt Wanderwege nach Barichara, aber Sie k\u00f6nnen auch ein Tuktuk nehmen.     <\/span><\/p>\n<p><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/naarcolombia.com\/wp-content\/uploads\/2024\/06\/casa-manahaim_hotel_barichara_colombia-300x200.jpeg\" width=\"300\" height=\"200\" alt=\"\" class=\"wp-image-253570 alignnone size-medium\"><\/span><\/p>\n<p>Sehen Sie sich unten weitere Hoteltipps f\u00fcr Barichara an.<\/p>\n<p>[\/et_pb_testimonial][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;20px||34px|||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; text_font=&#8221;|||||on|||&#8221; text_text_color=&#8221;#000000&#8243; header_font=&#8221;||||||||&#8221; header_4_font=&#8221;|700||on|||||&#8221; header_4_font_size=&#8221;12px&#8221; header_4_letter_spacing=&#8221;2px&#8221; header_4_line_height=&#8221;1.8em&#8221; background_color=&#8221;#f5f5f5&#8243; width=&#8221;100%&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;10px||4px|0px|false|false&#8221; custom_padding=&#8221;15px|20px|20px|23px|false|false&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; border_width_all=&#8221;2px&#8221; border_color_all=&#8221;#ffffff&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong>$ Preisspanne bis zu $25<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>$$ Preisspanne $25 &#8211; $75<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>$$$ Preisspanne \u00fcber $75<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.16&#8243; width=&#8221;100%&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;|auto||12px||&#8221; custom_padding=&#8221;|22px|18px|14px||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;$&#8221; image=&#8221;https:\/\/naarcolombia.com\/wp-content\/uploads\/2022\/05\/la-Pacha-hostel-Barichara-Colombia-1.jpeg&#8221; _builder_version=&#8221;4.17.3&#8243; header_font=&#8221;|700|||||||&#8221; header_text_align=&#8221;center&#8221; header_font_size=&#8221;30px&#8221; animation=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<ul>\n<li><a href=\"https:\/\/www.booking.com\/hotel\/co\/la-pacha-hostel.nl.html?aid=7906433&amp;no_rooms=1&amp;group_adults=2%201%20-%201%20of%201\" target=\"_blank\" rel=\"noopener\"><span>La Pacha Herberge  <\/span><\/a><span><\/span><\/li>\n<li><a href=\"https:\/\/www.booking.com\/hotel\/co\/la-juanita-hostel-barichara.nl.html?aid=7906433&amp;no_rooms=1&amp;group_adults=2\" target=\"_blank\" rel=\"noopener\">La Juanita Jugendherberge Barichara<\/a><\/li>\n<li><a href=\"https:\/\/www.booking.com\/hotel\/co\/artepolis-barichara.nl.html?aid=7906433&amp;no_rooms=1&amp;group_adults=2\" target=\"_blank\" rel=\"noopener\">Artepolis<\/a><\/li>\n<li><a href=\"https:\/\/www.booking.com\/hotel\/co\/mi-ranchito-centro.nl.html?aid=7906433&amp;no_rooms=1&amp;group_adults=2\" target=\"_blank\" rel=\"noopener\">Mi Ranchito-Centro<\/a><\/li>\n<li><a href=\"https:\/\/www.booking.com\/hotel\/co\/tinto-hostel.nl.html?aid=7906433&amp;no_rooms=1&amp;group_adults=2\" target=\"_blank\" rel=\"noopener\">Herberge Tinto<\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;$$&#8221; image=&#8221;https:\/\/naarcolombia.com\/wp-content\/uploads\/2022\/05\/Posada-Suenos-de-Antonio-2-Barichara-Colombia.jpeg&#8221; _builder_version=&#8221;4.22.1&#8243; header_font=&#8221;|700|||||||&#8221; header_text_align=&#8221;center&#8221; header_font_size=&#8221;30px&#8221; custom_margin=&#8221;||28px|||&#8221; custom_padding=&#8221;|||9px||&#8221; animation=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<ul>\n<li><a href=\"https:\/\/www.booking.com\/hotel\/co\/posada-de-versalles.nl.html?aid=7906433&amp;sid=8273bc9d814a064171a436a1f71ecd31&amp;all_sr_blocks=984737708_371094118_2_9_0;checkin=2023-09-06;checkout=2023-09-07;dist=0;group_adults=2;group_children=0;hapos=1;highlighted_blocks=984737708_371094118_2_9_0;hpos=1;matching_block_id=984737708_371094118_2_9_0;no_rooms=1;req_adults=2;req_children=0;room1=A%2CA;sb_price_type=total;sr_order=distance_from_search;sr_pri_blocks=984737708_371094118_2_9_0__16100000;srepoch=1693083128;srpvid=5eb292b9ec200076;type=total;ucfs=1hotelTmpl\" target=\"_blank\" rel=\"noopener\">Posada Sue\u00f1os de Antonio<\/a><\/li>\n<li><a href=\"https:\/\/www.booking.com\/hotel\/co\/la-loma-hostal.nl.html?aid=7906433&amp;no_rooms=1&amp;group_adults=2\" target=\"_blank\" rel=\"noopener\">La Loma Hotel Barichara<\/a><\/li>\n<li><a href=\"https:\/\/www.booking.com\/hotel\/co\/finca-buenos-aires-barichara.nl.html?aid=7906433&amp;no_rooms=1&amp;group_adults=2\" target=\"_blank\" rel=\"noopener\">Hotel Buenosaires Barichara<\/a><\/li>\n<li><a href=\"https:\/\/www.booking.com\/hotel\/co\/casa-aparicio-lopez.nl.html?aid=7906433&amp;no_rooms=1&amp;group_adults=2\" target=\"_blank\" rel=\"noopener\">Casa Aparicio Lopez<\/a><\/li>\n<li><a href=\"https:\/\/www.booking.com\/hotel\/co\/serrania-del-viento-barichara.nl.html?aid=7906433&amp;no_rooms=1&amp;group_adults=2\" target=\"_blank\" rel=\"noopener\">Serrania del Viento<\/a><\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.booking.com\/hotel\/co\/adriana-39-s-bambu-lodge.en-gb.html?aid=304142;label=opensearch-plugin;sid=9844c3d46bf9370f681a74010d683bc6;all_sr_blocks=216695801_167453698_2_34_0;checkin=2021-04-16;checkout=2021-04-19;dest_id=-585862;dest_type=city;dist=0;group_adults=2;group_children=0;hapos=1;highlighted_blocks=216695801_167453698_2_34_0;hpos=1;no_rooms=1;room1=A%2CA;sb_price_type=total;sr_order=popularity;sr_pri_blocks=216695801_167453698_2_34_0__62100000;srepoch=1616076368;srpvid=14f86327dba201a8;type=total;ucfs=1hotelTmpl\"><span><\/span><\/a><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;$$$&#8221; image=&#8221;https:\/\/naarcolombia.com\/wp-content\/uploads\/2022\/05\/Casa-Barichara-Boutique-Colombia.jpeg&#8221; _builder_version=&#8221;4.17.3&#8243; header_font=&#8221;|700|||||||&#8221; header_text_align=&#8221;center&#8221; header_font_size=&#8221;30px&#8221; custom_margin=&#8221;||12px|||&#8221; custom_padding=&#8221;|||9px||&#8221; animation=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<ul>\n<li><a href=\"https:\/\/www.booking.com\/hotel\/co\/posada-del-campanario.nl.html?aid=7906433&amp;no_rooms=1&amp;group_adults=2\" target=\"_blank\" rel=\"noopener\">Posada del Campanario<\/a><\/li>\n<li><a href=\"https:\/\/www.booking.com\/hotel\/co\/casa-barichara-del-pueblo.nl.html?aid=7906433&amp;no_rooms=1&amp;group_adults=2\" target=\"_blank\" rel=\"noopener\">Casa Barichara Boutique<\/a><\/li>\n<li><a href=\"https:\/\/www.booking.com\/hotel\/co\/boutique-venturi.nl.html?aid=7906433&amp;no_rooms=1&amp;group_adults=2\" target=\"_blank\" rel=\"noopener\">Hotel Boutique Venturi<\/a><\/li>\n<li><a href=\"https:\/\/www.booking.com\/hotel\/co\/casa-oniri-boutique.nl.html?aid=7906433&amp;no_rooms=1&amp;group_adults=2\" target=\"_blank\" rel=\"noopener\">Casa Oniri Hotel Boutique<\/a><\/li>\n<li><a href=\"https:\/\/www.booking.com\/hotel\/co\/nativo-glamping.nl.html?aid=7906433&amp;no_rooms=1&amp;group_adults=2\" target=\"_blank\" rel=\"noopener\">Nativo Glamping<\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.16&#8243; custom_margin=&#8221;9px|auto|35px|auto|false|false&#8221; custom_padding=&#8221;30px||23px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_button button_url=&#8221;https:\/\/www.booking.com\/searchresults.nl.html?city=-577966&amp;aid=7906433&amp;no_rooms=1&amp;group_adults=2&#8243; url_new_window=&#8221;on&#8221; button_text=&#8221;Mehr Hotels in Barichara&#8221; button_alignment=&#8221;center&#8221; _builder_version=&#8221;4.17.3&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;18px&#8221; button_bg_color=&#8221;#0c71c3&#8243; button_border_color=&#8221;rgba(0,0,0,0)&#8221; button_border_radius=&#8221;0px&#8221; button_letter_spacing=&#8221;1px&#8221; button_font=&#8221;Noto Sans|700|||||||&#8221; button_icon=&#8221;&#x24;||divi||400&#8243; button_on_hover=&#8221;off&#8221; background_layout=&#8221;dark&#8221; custom_margin=&#8221;4px|||||&#8221; custom_padding=&#8221;16px|60px|16px|60px|true|true&#8221; animation_direction=&#8221;left&#8221; box_shadow_style=&#8221;preset4&#8243; box_shadow_horizontal=&#8221;-10px&#8221; box_shadow_vertical=&#8221;0px&#8221; box_shadow_color=&#8221;#ffd07e&#8221; disabled=&#8221;on&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;|auto|-6px|auto|false|false&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_code _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||21px|||&#8221; global_colors_info=&#8221;{}&#8221;]<ins class=\"bookingaff\" data-aid=\"2245558\" data-target_aid=\"2245558\" data-prod=\"map\" data-width=\"100%\" data-height=\"590\" data-lang=\"nl\" data-currency=\"EUR\" data-dest_id=\"0\" data-dest_type=\"landmark\" data-latitude=\"6.635849\" data-longitude=\"-73.223409\" data-landmark_name=\"Barichara\" data-mwhsb=\"0\" data-address=\"Barichara, Santander, Colombia\"><!-- [et_pb_line_break_holder] -->    <!-- Anything inside will go away once widget is loaded. --><!-- [et_pb_line_break_holder] -->        <a href=\"\/\/www.booking.com?aid=2245558\">Booking.com<\/a><!-- [et_pb_line_break_holder] --><\/ins><!-- [et_pb_line_break_holder] --><script type=\"text\/javascript\"><!-- [et_pb_line_break_holder] -->    (function(d, sc, u) {<!-- [et_pb_line_break_holder] -->      var s = d.createElement(sc), p = d.getElementsByTagName(sc)[0];<!-- [et_pb_line_break_holder] -->      s.type = 'text\/javascript';<!-- [et_pb_line_break_holder] -->      s.async = true;<!-- [et_pb_line_break_holder] -->      s.src = u + '?v=' + (+new Date());<!-- [et_pb_line_break_holder] -->      p.parentNode.insertBefore(s,p);<!-- [et_pb_line_break_holder] -->      })(document, 'script', '\/\/cf.bstatic.com\/static\/affiliate_base\/js\/flexiproduct.js');<!-- [et_pb_line_break_holder] --><\/script>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Maintenance&#8221; _builder_version=&#8221;4.18.0&#8243; custom_margin=&#8221;|0px||0px|false|true&#8221; custom_margin_tablet=&#8221;|0%|0%|0%||true&#8221; custom_margin_phone=&#8221;&#8221; custom_margin_last_edited=&#8221;on|desktop&#8221; custom_padding=&#8221;33px||25px|||&#8221; border_color_all=&#8221;#ffd07e&#8221; border_width_right=&#8221;0vw&#8221; border_color_right=&#8221;#21468B&#8221; border_color_left=&#8221;#EABB3F&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; min_height=&#8221;129px&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text module_id=&#8221;praktische-info-mompox&#8221; _builder_version=&#8221;4.27.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Noto Sans|700|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#ffffff&#8221; header_2_font_size=&#8221;48px&#8221; header_2_line_height=&#8221;1.2em&#8221; background_color=&#8221;#1b4242&#8243; text_orientation=&#8221;center&#8221; custom_margin=&#8221;||35px||false|false&#8221; custom_padding=&#8221;10px||10px||false|false&#8221; hover_enabled=&#8221;0&#8243; header_2_font_size_tablet=&#8221;&#8221; header_2_font_size_phone=&#8221;28px&#8221; header_2_font_size_last_edited=&#8221;on|desktop&#8221; header_2_text_shadow_style=&#8221;preset1&#8243; border_radii=&#8221;on|10px|10px|10px|10px&#8221; box_shadow_style=&#8221;preset1&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h2 style=\"text-align: center;\">Wichtige Infos A-Z<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.16&#8243; custom_margin=&#8221;|auto|26px|auto||&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_accordion open_toggle_text_color=&#8221;#000000&#8243; open_toggle_background_color=&#8221;#fcbf49&#8243; closed_toggle_text_color=&#8221;#ffffff&#8221; closed_toggle_background_color=&#8221;#f77f00&#8243; icon_color=&#8221;#ffffff&#8221; use_icon_font_size=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; closed_toggle_font=&#8221;|600|||||||&#8221; body_text_color=&#8221;#000000&#8243; custom_margin=&#8221;26px|||2px||&#8221; hover_enabled=&#8221;0&#8243; border_radii=&#8221;on|10px|10px|10px|10px&#8221; border_width_all=&#8221;3px&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][et_pb_accordion_item title=&#8221;Einheimische &amp; Sprache&#8221; open=&#8221;on&#8221; open_toggle_background_color=&#8221;#f5f5f5&#8243; closed_toggle_background_color=&#8221;#1b4242&#8243; _builder_version=&#8221;4.27.4&#8243; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; toggle_font=&#8221;|600|||||||&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p><span style=\"font-weight: 400;\">Im Allgemeinen wird nur wenig Englisch gesprochen. Ein Wort Spanisch ist sicherlich hilfreich und wirkt Wunder, um mit den Einheimischen in Kontakt zu kommen.   <\/span><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=&#8221;Impfungen&#8221; open_toggle_background_color=&#8221;#f5f5f5&#8243; closed_toggle_background_color=&#8221;#1b4242&#8243; _builder_version=&#8221;4.27.4&#8243; global_colors_info=&#8221;{}&#8221; toggle_font=&#8221;|600|||||||&#8221; open=&#8221;off&#8221;]<\/p>\n<p><span style=\"font-weight: 400;\">F\u00fcr Barichara sind keine Impfungen erforderlich.<\/span><strong><\/strong><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=&#8221;Was Sie mitbringen sollten&#8221; open_toggle_background_color=&#8221;#f5f5f5&#8243; closed_toggle_background_color=&#8221;#1b4242&#8243; _builder_version=&#8221;4.27.4&#8243; global_colors_info=&#8221;{}&#8221; toggle_font=&#8221;|600|||||||&#8221; open=&#8221;off&#8221;]<\/p>\n<ul>\n<li><span style=\"font-weight: 400;\">Wanderschuhe (die Stra\u00dfen f\u00fchren bergauf und bergab, gutes Schuhwerk ist also ein Muss)<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">M\u00fctze oder Hut  <\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Sonnenschutzmittel<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Wasserthermos<\/span><\/li>\n<\/ul>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=&#8221;Sicherheit&#8221; open_toggle_background_color=&#8221;#f5f5f5&#8243; closed_toggle_background_color=&#8221;#1b4242&#8243; _builder_version=&#8221;4.27.4&#8243; global_colors_info=&#8221;{}&#8221; toggle_font=&#8221;|600|||||||&#8221; open=&#8221;off&#8221;]<\/p>\n<p><span style=\"font-weight: 400;\">Barichara und der Wanderweg nach Guane gelten als sicher. Es ist immer gut, sich im Zweifelsfall bei Einheimischen zu erkundigen, zum Beispiel beim Hotelpersonal.   <\/span><\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=&#8221;Wifi&#8221; open_toggle_background_color=&#8221;#f5f5f5&#8243; closed_toggle_background_color=&#8221;#1b4242&#8243; _builder_version=&#8221;4.27.4&#8243; global_colors_info=&#8221;{}&#8221; toggle_font=&#8221;|600|||||||&#8221; open=&#8221;off&#8221;]<\/p>\n<p>Die meisten Hotels verf\u00fcgen \u00fcber WLAN, aber die Verbindung ist nicht immer stabil, insbesondere wenn Sie in einem Hotel wohnen, das weiter vom Zentrum entfernt ist.<\/p>\n<p>[\/et_pb_accordion_item][\/et_pb_accordion][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.16&#8243; custom_margin=&#8221;10px|auto|0px|auto|false|false&#8221; custom_padding=&#8221;20px||35px||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; custom_css_main_element=&#8221;display: flex;||    justify-content: center;&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_button button_url=&#8221;https:\/\/colombiamyway.com\/de\/bogota-und-nord-bogota\/&#8221; url_new_window=&#8221;on&#8221; button_text=&#8221;\u2190 Bogot\u00e1 und Nord-Bogot\u00e1&#8221; button_alignment=&#8221;left&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_color=&#8221;#000000&#8243; button_bg_color=&#8221;#EABB3F&#8221; button_border_width=&#8221;2px&#8221; button_border_color=&#8221;#ffffff&#8221; button_border_radius=&#8221;10px&#8221; button_font=&#8221;|600|||||||&#8221; button_icon=&#8221;&#x48;||divi||400&#8243; button_icon_placement=&#8221;left&#8221; button_text_size_tablet=&#8221;17px&#8221; button_text_size_phone=&#8221;16px&#8221; button_text_size_last_edited=&#8221;on|phone&#8221; custom_css_main_element=&#8221;display: inline-block;||    margin: 0px 10px 0px 0px!important;&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p><div class=\"et_pb_module lwp_divi_breadcrumbs lwp_divi_breadcrumbs_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"lwp-breadcrumbs\"> <span class=\"before\"><\/span> <span vocab=\"https:\/\/schema.org\/\" typeof=\"BreadcrumbList\"><span property=\"itemListElement\" typeof=\"ListItem\"><a property=\"item\" typeof=\"WebPage\" href=\"https:\/\/colombiamyway.com\/de\/\" class=\"home\"><span property=\"name\">Home<\/span><\/a><meta property=\"position\" content=\"1\"><\/span> <span class=\"separator et-pb-icon\">&#x39;<\/span> <\/span><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\u00dcber BaricharaDiese sch\u00f6ne Kolonialstadt liegt 120 km von Bucaramanga entfernt, in der Region Santander. Barichara liegt 1300 Meter \u00fcber dem Meeresspiegel und beheimatet etwa 10.000 Menschen. Die Kulisse ist beeindruckend, in den Bergen, am Rande des Chicamocha Canyons, der auch der &#8220;Grand Canyon&#8221; von Kolumbien genannt wird. San Gil &#8211; Kolumbiens Hotspot [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":258716,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[266],"tags":[],"class_list":["post-262417","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bogota-und-n-bogota"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alles \u00fcber Barichara - Colombia My Way<\/title>\n<meta name=\"description\" content=\"In diesem Reisef\u00fchrer finden Sie alles \u00fcber die Kolonialstadt Barichara. Die besten Unternehmungen, die sch\u00f6nsten Hotels und die besten Restaurants.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/colombiamyway.com\/de\/alles-ueber-barichara\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alles \u00fcber Barichara - Colombia My Way\" \/>\n<meta property=\"og:description\" content=\"In diesem Reisef\u00fchrer finden Sie alles \u00fcber die Kolonialstadt Barichara. Die besten Unternehmungen, die sch\u00f6nsten Hotels und die besten Restaurants.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/colombiamyway.com\/de\/alles-ueber-barichara\/\" \/>\n<meta property=\"og:site_name\" content=\"Colombia My Way\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61571407164514\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-13T00:14:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-06T18:16:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/colombiamyway.com\/wp-content\/uploads\/2022\/05\/Barichara_Santander.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"612\" \/>\n\t<meta property=\"og:image:height\" content=\"410\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"J\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"J\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"29\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/alles-ueber-barichara\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/alles-ueber-barichara\\\/\"},\"author\":{\"name\":\"J\",\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/#\\\/schema\\\/person\\\/011d515d7815ef4a06a1d4f782f06711\"},\"headline\":\"Alles \u00fcber Barichara\",\"datePublished\":\"2022-09-13T00:14:13+00:00\",\"dateModified\":\"2025-09-06T18:16:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/alles-ueber-barichara\\\/\"},\"wordCount\":5759,\"publisher\":{\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/alles-ueber-barichara\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/colombiamyway.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Barichara_Santander.jpg\",\"articleSection\":[\"Bogot\u00e1 und N-Bogot\u00e1\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/alles-ueber-barichara\\\/\",\"url\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/alles-ueber-barichara\\\/\",\"name\":\"Alles \u00fcber Barichara - Colombia My Way\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/alles-ueber-barichara\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/alles-ueber-barichara\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/colombiamyway.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Barichara_Santander.jpg\",\"datePublished\":\"2022-09-13T00:14:13+00:00\",\"dateModified\":\"2025-09-06T18:16:53+00:00\",\"description\":\"In diesem Reisef\u00fchrer finden Sie alles \u00fcber die Kolonialstadt Barichara. Die besten Unternehmungen, die sch\u00f6nsten Hotels und die besten Restaurants.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/alles-ueber-barichara\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/colombiamyway.com\\\/de\\\/alles-ueber-barichara\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/alles-ueber-barichara\\\/#primaryimage\",\"url\":\"https:\\\/\\\/colombiamyway.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Barichara_Santander.jpg\",\"contentUrl\":\"https:\\\/\\\/colombiamyway.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Barichara_Santander.jpg\",\"width\":612,\"height\":410},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/alles-ueber-barichara\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/startseite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alles \u00fcber Barichara\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/\",\"name\":\"Colombia My Way\",\"description\":\"The Guide for the Independent Traveler\",\"publisher\":{\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/#organization\",\"name\":\"Colombia My Way\",\"url\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/colombiamyway.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Green-Modern-and-Minimalistic-Travel-Typography-Logo-2.png?fit=500%2C500&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/colombiamyway.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Green-Modern-and-Minimalistic-Travel-Typography-Logo-2.png?fit=500%2C500&ssl=1\",\"width\":500,\"height\":500,\"caption\":\"Colombia My Way\"},\"image\":{\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61571407164514\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/#\\\/schema\\\/person\\\/011d515d7815ef4a06a1d4f782f06711\",\"name\":\"J\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf3b73a22b0de0f97a1211e232e3f892dfb68f20041d088345d383fffd417f9c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf3b73a22b0de0f97a1211e232e3f892dfb68f20041d088345d383fffd417f9c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf3b73a22b0de0f97a1211e232e3f892dfb68f20041d088345d383fffd417f9c?s=96&d=mm&r=g\",\"caption\":\"J\"},\"url\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/author\\\/divisitescuracao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alles \u00fcber Barichara - Colombia My Way","description":"In diesem Reisef\u00fchrer finden Sie alles \u00fcber die Kolonialstadt Barichara. Die besten Unternehmungen, die sch\u00f6nsten Hotels und die besten Restaurants.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/colombiamyway.com\/de\/alles-ueber-barichara\/","og_locale":"de_DE","og_type":"article","og_title":"Alles \u00fcber Barichara - Colombia My Way","og_description":"In diesem Reisef\u00fchrer finden Sie alles \u00fcber die Kolonialstadt Barichara. Die besten Unternehmungen, die sch\u00f6nsten Hotels und die besten Restaurants.","og_url":"https:\/\/colombiamyway.com\/de\/alles-ueber-barichara\/","og_site_name":"Colombia My Way","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61571407164514","article_published_time":"2022-09-13T00:14:13+00:00","article_modified_time":"2025-09-06T18:16:53+00:00","og_image":[{"width":612,"height":410,"url":"https:\/\/colombiamyway.com\/wp-content\/uploads\/2022\/05\/Barichara_Santander.jpg","type":"image\/jpeg"}],"author":"J","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"J","Gesch\u00e4tzte Lesezeit":"29\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/colombiamyway.com\/de\/alles-ueber-barichara\/#article","isPartOf":{"@id":"https:\/\/colombiamyway.com\/de\/alles-ueber-barichara\/"},"author":{"name":"J","@id":"https:\/\/colombiamyway.com\/de\/#\/schema\/person\/011d515d7815ef4a06a1d4f782f06711"},"headline":"Alles \u00fcber Barichara","datePublished":"2022-09-13T00:14:13+00:00","dateModified":"2025-09-06T18:16:53+00:00","mainEntityOfPage":{"@id":"https:\/\/colombiamyway.com\/de\/alles-ueber-barichara\/"},"wordCount":5759,"publisher":{"@id":"https:\/\/colombiamyway.com\/de\/#organization"},"image":{"@id":"https:\/\/colombiamyway.com\/de\/alles-ueber-barichara\/#primaryimage"},"thumbnailUrl":"https:\/\/colombiamyway.com\/wp-content\/uploads\/2022\/05\/Barichara_Santander.jpg","articleSection":["Bogot\u00e1 und N-Bogot\u00e1"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/colombiamyway.com\/de\/alles-ueber-barichara\/","url":"https:\/\/colombiamyway.com\/de\/alles-ueber-barichara\/","name":"Alles \u00fcber Barichara - Colombia My Way","isPartOf":{"@id":"https:\/\/colombiamyway.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/colombiamyway.com\/de\/alles-ueber-barichara\/#primaryimage"},"image":{"@id":"https:\/\/colombiamyway.com\/de\/alles-ueber-barichara\/#primaryimage"},"thumbnailUrl":"https:\/\/colombiamyway.com\/wp-content\/uploads\/2022\/05\/Barichara_Santander.jpg","datePublished":"2022-09-13T00:14:13+00:00","dateModified":"2025-09-06T18:16:53+00:00","description":"In diesem Reisef\u00fchrer finden Sie alles \u00fcber die Kolonialstadt Barichara. Die besten Unternehmungen, die sch\u00f6nsten Hotels und die besten Restaurants.","breadcrumb":{"@id":"https:\/\/colombiamyway.com\/de\/alles-ueber-barichara\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/colombiamyway.com\/de\/alles-ueber-barichara\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/colombiamyway.com\/de\/alles-ueber-barichara\/#primaryimage","url":"https:\/\/colombiamyway.com\/wp-content\/uploads\/2022\/05\/Barichara_Santander.jpg","contentUrl":"https:\/\/colombiamyway.com\/wp-content\/uploads\/2022\/05\/Barichara_Santander.jpg","width":612,"height":410},{"@type":"BreadcrumbList","@id":"https:\/\/colombiamyway.com\/de\/alles-ueber-barichara\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/colombiamyway.com\/de\/startseite\/"},{"@type":"ListItem","position":2,"name":"Alles \u00fcber Barichara"}]},{"@type":"WebSite","@id":"https:\/\/colombiamyway.com\/de\/#website","url":"https:\/\/colombiamyway.com\/de\/","name":"Colombia My Way","description":"The Guide for the Independent Traveler","publisher":{"@id":"https:\/\/colombiamyway.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/colombiamyway.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/colombiamyway.com\/de\/#organization","name":"Colombia My Way","url":"https:\/\/colombiamyway.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/colombiamyway.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/colombiamyway.com\/wp-content\/uploads\/2024\/12\/Green-Modern-and-Minimalistic-Travel-Typography-Logo-2.png?fit=500%2C500&ssl=1","contentUrl":"https:\/\/i0.wp.com\/colombiamyway.com\/wp-content\/uploads\/2024\/12\/Green-Modern-and-Minimalistic-Travel-Typography-Logo-2.png?fit=500%2C500&ssl=1","width":500,"height":500,"caption":"Colombia My Way"},"image":{"@id":"https:\/\/colombiamyway.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61571407164514"]},{"@type":"Person","@id":"https:\/\/colombiamyway.com\/de\/#\/schema\/person\/011d515d7815ef4a06a1d4f782f06711","name":"J","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/bf3b73a22b0de0f97a1211e232e3f892dfb68f20041d088345d383fffd417f9c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bf3b73a22b0de0f97a1211e232e3f892dfb68f20041d088345d383fffd417f9c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bf3b73a22b0de0f97a1211e232e3f892dfb68f20041d088345d383fffd417f9c?s=96&d=mm&r=g","caption":"J"},"url":"https:\/\/colombiamyway.com\/de\/author\/divisitescuracao\/"}]}},"_links":{"self":[{"href":"https:\/\/colombiamyway.com\/de\/wp-json\/wp\/v2\/posts\/262417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/colombiamyway.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/colombiamyway.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/colombiamyway.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/colombiamyway.com\/de\/wp-json\/wp\/v2\/comments?post=262417"}],"version-history":[{"count":3,"href":"https:\/\/colombiamyway.com\/de\/wp-json\/wp\/v2\/posts\/262417\/revisions"}],"predecessor-version":[{"id":269187,"href":"https:\/\/colombiamyway.com\/de\/wp-json\/wp\/v2\/posts\/262417\/revisions\/269187"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/colombiamyway.com\/de\/wp-json\/wp\/v2\/media\/258716"}],"wp:attachment":[{"href":"https:\/\/colombiamyway.com\/de\/wp-json\/wp\/v2\/media?parent=262417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/colombiamyway.com\/de\/wp-json\/wp\/v2\/categories?post=262417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/colombiamyway.com\/de\/wp-json\/wp\/v2\/tags?post=262417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}