{"id":262470,"date":"2020-07-08T18:06:25","date_gmt":"2020-07-08T22:06:25","guid":{"rendered":"https:\/\/colombiamyway.com\/von-einem-engel-in-santa-rosa-de-cabal-gerettet-2\/"},"modified":"2025-09-06T15:25:38","modified_gmt":"2025-09-06T19:25:38","slug":"von-einem-engel-in-santa-rosa-de-cabal-gerettet","status":"publish","type":"post","link":"https:\/\/colombiamyway.com\/de\/von-einem-engel-in-santa-rosa-de-cabal-gerettet\/","title":{"rendered":"Von einem Engel in Santa Rosa de Cabal gerettet"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; theme_builder_area=&#8221;post_content&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; type=&#8221;4_4&#8243; theme_builder_area=&#8221;post_content&#8221;][lwp_divi_breadcrumbs _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; theme_builder_area=&#8221;post_content&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;][\/lwp_divi_breadcrumbs][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.4&#8243; module_alignment=&#8221;center&#8221; custom_margin=&#8221;0px|0px||0px|false|false&#8221; custom_padding=&#8221;35px|0px|50px|0px|false|false&#8221; top_divider_color=&#8221;#00701d&#8221; top_divider_height=&#8221;20px&#8221; bottom_divider_color=&#8221;#21468B&#8221; bottom_divider_height=&#8221;30px&#8221; border_width_all=&#8221;0px&#8221; border_color_all=&#8221;#5b8500&#8243; border_color_right=&#8221;#c90053&#8243; border_color_left=&#8221;#EABB3F&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.27.4&#8243; module_alignment=&#8221;center&#8221; custom_margin=&#8221;|276px||72px||&#8221; custom_padding=&#8221;32px|7px|35px|11px||&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.25.1&#8243; header_font=&#8221;|600||||on|||&#8221; header_text_color=&#8221;#000000&#8243; custom_margin=&#8221;||38px|||&#8221; custom_padding=&#8221;|||36px||&#8221; border_radii=&#8221;on|2px|2px|2px|2px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Medizinische Versorgung in Kolumbien, unsere eigene Geschichte<\/h1>\n<p>[\/et_pb_text][et_pb_testimonial _builder_version=&#8221;4.27.4&#8243; body_font_size=&#8221;25px&#8221; custom_margin=&#8221;||31px|||&#8221; body_font_size_tablet=&#8221;&#8221; body_font_size_phone=&#8221;&#8221; body_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Als wir am Hotel ankamen, stand ein Krankenwagen mit Blaulicht vor dem Tor. Das waren meine <em>Angels<\/em>! Als ich &#8211; ziemlich ver\u00e4rgert &#8211; fragte, ob die blinkenden Lichter ausgeschaltet werden k\u00f6nnten, kam das f\u00fcr sie nicht in Frage. <\/p>\n<p>[\/et_pb_testimonial][et_pb_text _builder_version=&#8221;4.27.4&#8243; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;#282828&#8243; text_font_size=&#8221;18px&#8221; text_letter_spacing=&#8221;1px&#8221; width=&#8221;98%&#8221; custom_margin=&#8221;-26px|-9px|3px|3px||&#8221; custom_padding=&#8221;|10px||6px||&#8221; link_option_url_new_window=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong><\/strong><\/p>\n<p><strong> <\/strong><\/p>\n<p><strong><\/strong>W\u00e4hrend meines Aufenthalts im Kaffeedreieck habe ich mir eine schlimme Erk\u00e4ltung eingefangen. An sich nichts Besorgniserregendes, aber mit der akuten Bronchitis aus einem fr\u00fcheren Urlaub noch im Hinterkopf wurde ich ein wenig nerv\u00f6s. Von unserem Hotel <a href=\"https:\/\/www.booking.com\/searchresults.nl.html?aid=7906433&amp;city=-579209&amp;no_rooms=1&amp;group_adults=2&amp;offset=25\" target=\"_blank\" rel=\"noopener\" title=\"Hotel in Calarc\u00e1\"><strong>Hotel in Calarc\u00e1<\/strong><\/a> w\u00fcrden wir zu den <a href=\"https:\/\/colombiamyway.com\/de\/thermalquellen-santa-rosa-de-cabal\/\" target=\"_blank\" rel=\"noopener\"><strong>hei\u00dfen Quellen in Santa Rosa de Cabal<\/strong><\/a> von denen wir so viel geh\u00f6rt hatten, und dann w\u00fcrde ich allein zum <a href=\"https:\/\/www.booking.com\/hotel\/co\/termales-del-ruiz.nl.html?aid=7906433&amp;no_rooms=1&amp;group_adults=2\" target=\"_blank\" rel=\"noopener\" title=\"Hotel Termales del Ruiz\"><strong>Hotel Termales del Ruiz<\/strong><\/a>in der N\u00e4he <a href=\"https:\/\/colombiamyway.com\/de\/los-nevados-national-park\/\" target=\"_blank\" rel=\"noopener\" title=\"los Nevados National Park\"><strong>los Nevados National Park<\/strong><\/a>. Dieser Park liegt etwa 3500 Meter \u00fcber dem Meeresspiegel und das Hotel, das ich gebucht hatte, lag mitten im Nirgendwo. Nicht wirklich ein Ort, um krank zu werden!    <\/p>\n<p><strong>Angeles al Llamado<\/strong><br \/>W\u00e4hrend ich noch \u00fcberlegte, was ich tun sollte, fing meine kolumbianische Reisebegleiterin an, wie wild zu googeln. Auf Facebook fand sie <em>Angeles al Llamado <\/em>, ein medizinisches Team, das von Pereira aus Hausbesuche macht. Pereira ist nicht weit von Santa Rosa de Cabal entfernt, wohin wir an diesem Morgen fahren w\u00fcrden. Sie arrangierte, dass die <em>Angeles<\/em> zu unserem <a href=\"https:\/\/www.booking.com\/searchresults.nl.html?city=-598893&amp;aid=7906433&amp;no_rooms=1&amp;group_adults=2\" target=\"_blank\" rel=\"noopener\" title=\"Hotel in Santa Rosa de Cabal\"><strong>Hotel in Santa Rosa de Cabal<\/strong> <\/a>f\u00fcr eine Konsultation.   <\/p>\n<p><strong><\/strong>Nachdem wir unsere voraussichtliche Ankunftszeit und Adresse angegeben hatten, konnten wir fr\u00fchst\u00fccken, aus dem Hotel auschecken und nach Santa Rosa de Cabal fahren. Als wir am Hotel ankamen, stand ein Krankenwagen mit Blaulicht vor dem Tor! <\/p>\n<p><strong>\u00bfQu\u00e9 paso?<br \/><\/strong>Der Hotelangestellte war bereits nach drau\u00dfen gelaufen, um zu sehen, was los war. Das waren meine <em>Angels<\/em>! Als ich das Personal des Krankenwagens ganz verlegen fragte, ob man die blinkenden Lichter abschalten k\u00f6nne, kam das f\u00fcr sie nicht in Frage. Die blinkenden Lichter gingen erst aus, als sie an der Rezeption des Hotels ankamen, eine Standardprozedur!  <\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;#282828&#8243; text_font_size=&#8221;18px&#8221; text_letter_spacing=&#8221;1px&#8221; custom_margin=&#8221;-17px||14px|||&#8221; custom_padding=&#8221;13px|10px||8px||&#8221; link_option_url_new_window=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong>Spanischer Fragebogen<\/strong><br \/>Nachdem ich mich an der Hotelrezeption eingerichtet hatte, schossen der Arzt und die Krankenschwester mit einigen Fragen auf mich ein. Normalerweise komme ich mit Spanisch ganz gut zurecht, aber jetzt war ich sehr froh, dass meine kolumbianische Reisebegleiterin mir genau erkl\u00e4ren konnte, was mit mir los war. <\/p>\n<p><strong>Check, check, doublecheck<\/strong><br \/>Nachdem ich den Fragebogen ausgef\u00fcllt hatte, wurde mein Blutdruck gemessen und meine Lunge und mein Rachen untersucht. Die Lunge war sauber, der Blutdruck in Ordnung und keine Bronchitis, oef! <\/p>\n<p>Ich hatte eine beginnende Halsentz\u00fcndung und bekam daf\u00fcr eine Spritze. (In meine Pobacke, was in Kolumbien ganz normal ist -:)). Au\u00dferdem wurde mir ein Rezept f\u00fcr Antibiotika, Hustensaft und zus\u00e4tzliche Vitamine verschrieben.  <\/p>\n<p><strong>Zum Los Nevados National Park oder nicht?<br \/><\/strong>Zun\u00e4chst war das medizinische Team nicht gl\u00fccklich \u00fcber meine geplante Reise in den Los Nevados National Park. Nachdem ich versprochen hatte, keine langen Wanderungen zu unternehmen, stimmten sie der Reise unter einer Bedingung zu: Ich musste mich in den n\u00e4chsten Tagen in Santa Rosa de Cabal gut ausruhen und mich f\u00fcr die K\u00e4lte gut kleiden. Nach einer herzlichen Verabschiedung stiegen meine <em>Engel<\/em> wieder in den Krankenwagen (ohne Blinklicht&#8230;).  <\/p>\n<p><b>Medikamenten-Lieferservice<\/b><br \/>Die Mitarbeiterin des Hotels war so freundlich, die Medikamente telefonisch in der Apotheke zu bestellen und sie zu liefern<em>(domicilio<\/em>). Was f\u00fcr ein perfekter Service! <\/p>\n<p><strong>Preisschild<br \/><\/strong>Was hat dieser Service gekostet?<br \/>-Konsultation einschlie\u00dflich Injektion: COP295,000\/$75<br \/>-Medikamente einschlie\u00dflich Lieferservice: COP85,500\/$23<br \/><span style=\"text-decoration: underline;\"><\/span><em>Angeles al Llamado<\/em> hat mir sogar eine Rechnung geschickt, mit der ich einen Antrag bei meiner Versicherung stellen konnte.<span style=\"text-decoration: underline;\"><br \/><\/span><\/p>\n<p><strong>Los Nevados, ich komme!<br \/><\/strong>Alles in allem war diese Beratung nicht billig, aber f\u00fcr mich war sie unbezahlbar. Da ich mich schnell erholt habe, konnte ich die Reise im Kaffeedreieck ohne Probleme fortsetzen. Ich hatte mich schon so lange darauf gefreut und es wurde eine tolle Reise.  <\/p>\n<p>Und das alles dank der netten Leute von <em>Angeles al llamado<\/em>!<\/p>\n<p><em>Geschrieben von: Jeanette<\/em><br \/><em>Reisedatum: M\u00e4rz 2019, aktualisiert September 2025<\/em><\/p>\n<p><strong>F\u00fcr weitere Informationen besuchen Sie bitte:<br \/><\/strong><strong><a href=\"https:\/\/www.facebook.com\/AngelesAlLlamado\/\" target=\"_blank\" rel=\"noopener noreferrer\">Angeles al Llamado auf Facebook<\/a><\/strong><\/p>\n<p>Sehen Sie sich unseren <strong><a href=\"https:\/\/colombiamyway.com\/de\/ein-fuehrer-durch-das-kolumbianische-kaffeedreieck\/\" target=\"_blank\" rel=\"noopener\">Reisef\u00fchrer Kaffeedreieck <\/a><\/strong><span style=\"text-decoration: underline;\"><\/span>f\u00fcr weitere Informationen \u00fcber diese Region und diesen Artikel \u00fcber die <a href=\"https:\/\/colombiamyway.com\/de\/medizinische-versorgung\/\" target=\"_blank\" rel=\"noopener\"><strong>medizinische Versorgung in Kolumbien<\/strong>.<\/a><\/p>\n<p>Hier finden Sie mehr Informationen \u00fcber die <a href=\"https:\/\/colombiamyway.com\/de\/thermalquellen-santa-rosa-de-cabal\/\" target=\"_blank\" rel=\"noopener\"><strong>hei\u00dfen Quellen in Santa Rosa de Cabal<\/strong><\/a> und den Ausflug zum <a href=\"https:\/\/colombiamyway.com\/de\/auf-tour-im-los-nevados-national-park\/\" target=\"_blank\" rel=\"noopener\"><strong>National Park los Nevados<\/strong><\/a> und das Hotel Termales del Ruiz, <a href=\"https:\/\/colombiamyway.com\/de\/ausflug-nach-termales-del-ruiz-abseits-der-ausgetretenen-pfade\/\" target=\"_blank\" rel=\"noopener\"><strong>das einzige Hotel in der N\u00e4he des Eingangs zum Park. <\/strong><\/a> <\/p>\n<p><em> <\/em><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||49px|||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_testimonial author=&#8221;Jeanette und Shelly&#8221; job_title=&#8221;Schriftsteller und Reisende&#8221; company_name=&#8221;Kolumbien Mein Weg&#8221; portrait_url=&#8221;https:\/\/colombiamyway.com\/wp-content\/uploads\/2024\/12\/Green-Modern-and-Minimalistic-Travel-Typography-Logo-2.png&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Wir nehmen keine direkten Zahlungen von Reiseveranstaltern oder Hotels f\u00fcr unsere Bewertungen an und bezahlen unsere Aufenthalte und Touren selbst. Jede Empfehlung basiert ausschlie\u00dflich auf unseren eigenen Erfahrungen und ehrlichen Meinungen. Einige unserer Links sind jedoch Affiliate-Links, d.h. wir erhalten eine kleine Provision, wenn Sie \u00fcber diese Links buchen. Diese Provision ist f\u00fcr Sie kostenlos und hilft uns, unsere Website zu unterhalten.   <\/p>\n<p>[\/et_pb_testimonial][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p><div class=\"et_pb_module lwp_divi_breadcrumbs lwp_divi_breadcrumbs_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"lwp-breadcrumbs\"> <span class=\"before\"><\/span> <span vocab=\"https:\/\/schema.org\/\" typeof=\"BreadcrumbList\"><span property=\"itemListElement\" typeof=\"ListItem\"><a property=\"item\" typeof=\"WebPage\" href=\"https:\/\/colombiamyway.com\/de\/\" class=\"home\"><span property=\"name\">Home<\/span><\/a><meta property=\"position\" content=\"1\"><\/span> <span class=\"separator et-pb-icon\">&#x39;<\/span> <\/span><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>Medizinische Versorgung in Kolumbien, unsere eigene GeschichteAls wir am Hotel ankamen, stand ein Krankenwagen mit Blaulicht vor dem Tor. Das waren meine Angels! Als ich &#8211; ziemlich ver\u00e4rgert &#8211; fragte, ob die blinkenden Lichter ausgeschaltet werden k\u00f6nnten, kam das f\u00fcr sie nicht in Frage. W\u00e4hrend meines Aufenthalts im Kaffeedreieck habe [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":259161,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[142,207],"tags":[],"class_list":["post-262470","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reiseberichte","category-reisefuhrer-fur-das-kolumbianische-kaffeedreieck"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Von einem Engel in Santa Rosa de Cabal gerettet - Colombia My Way<\/title>\n<meta name=\"description\" content=\"Medizinische Versorgung in Kolumbien? Hier k\u00f6nnen Sie \u00fcber unsere eigenen Erfahrungen mit einem &quot;Hausbesuch&quot; bei den \u00c4rzten von Angeles al Llamado aus Pereira lesen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/colombiamyway.com\/de\/von-einem-engel-in-santa-rosa-de-cabal-gerettet\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Von einem Engel in Santa Rosa de Cabal gerettet - Colombia My Way\" \/>\n<meta property=\"og:description\" content=\"Medizinische Versorgung in Kolumbien? Hier k\u00f6nnen Sie \u00fcber unsere eigenen Erfahrungen mit einem &quot;Hausbesuch&quot; bei den \u00c4rzten von Angeles al Llamado aus Pereira lesen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/colombiamyway.com\/de\/von-einem-engel-in-santa-rosa-de-cabal-gerettet\/\" \/>\n<meta property=\"og:site_name\" content=\"Colombia My Way\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61571407164514\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-08T22:06:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-06T19:25:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/colombiamyway.com\/wp-content\/uploads\/2020\/09\/Angeles-al-Llamado_Pereira_Colombia-copy.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"J\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"J\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/von-einem-engel-in-santa-rosa-de-cabal-gerettet\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/von-einem-engel-in-santa-rosa-de-cabal-gerettet\\\/\"},\"author\":{\"name\":\"J\",\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/#\\\/schema\\\/person\\\/011d515d7815ef4a06a1d4f782f06711\"},\"headline\":\"Von einem Engel in Santa Rosa de Cabal gerettet\",\"datePublished\":\"2020-07-08T22:06:25+00:00\",\"dateModified\":\"2025-09-06T19:25:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/von-einem-engel-in-santa-rosa-de-cabal-gerettet\\\/\"},\"wordCount\":1214,\"publisher\":{\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/von-einem-engel-in-santa-rosa-de-cabal-gerettet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/colombiamyway.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Angeles-al-Llamado_Pereira_Colombia-copy.jpg\",\"articleSection\":[\"Reiseberichte\",\"Reisef\u00fchrer f\u00fcr das kolumbianische Kaffeedreieck\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/von-einem-engel-in-santa-rosa-de-cabal-gerettet\\\/\",\"url\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/von-einem-engel-in-santa-rosa-de-cabal-gerettet\\\/\",\"name\":\"Von einem Engel in Santa Rosa de Cabal gerettet - Colombia My Way\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/von-einem-engel-in-santa-rosa-de-cabal-gerettet\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/von-einem-engel-in-santa-rosa-de-cabal-gerettet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/colombiamyway.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Angeles-al-Llamado_Pereira_Colombia-copy.jpg\",\"datePublished\":\"2020-07-08T22:06:25+00:00\",\"dateModified\":\"2025-09-06T19:25:38+00:00\",\"description\":\"Medizinische Versorgung in Kolumbien? Hier k\u00f6nnen Sie \u00fcber unsere eigenen Erfahrungen mit einem \\\"Hausbesuch\\\" bei den \u00c4rzten von Angeles al Llamado aus Pereira lesen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/von-einem-engel-in-santa-rosa-de-cabal-gerettet\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/colombiamyway.com\\\/de\\\/von-einem-engel-in-santa-rosa-de-cabal-gerettet\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/von-einem-engel-in-santa-rosa-de-cabal-gerettet\\\/#primaryimage\",\"url\":\"https:\\\/\\\/colombiamyway.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Angeles-al-Llamado_Pereira_Colombia-copy.jpg\",\"contentUrl\":\"https:\\\/\\\/colombiamyway.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Angeles-al-Llamado_Pereira_Colombia-copy.jpg\",\"width\":960,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/von-einem-engel-in-santa-rosa-de-cabal-gerettet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/startseite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Von einem Engel in Santa Rosa de Cabal gerettet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/\",\"name\":\"Colombia My Way\",\"description\":\"The Guide for the Independent Traveler\",\"publisher\":{\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/#organization\",\"name\":\"Colombia My Way\",\"url\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/colombiamyway.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Green-Modern-and-Minimalistic-Travel-Typography-Logo-2.png?fit=500%2C500&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/colombiamyway.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Green-Modern-and-Minimalistic-Travel-Typography-Logo-2.png?fit=500%2C500&ssl=1\",\"width\":500,\"height\":500,\"caption\":\"Colombia My Way\"},\"image\":{\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61571407164514\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/#\\\/schema\\\/person\\\/011d515d7815ef4a06a1d4f782f06711\",\"name\":\"J\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf3b73a22b0de0f97a1211e232e3f892dfb68f20041d088345d383fffd417f9c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf3b73a22b0de0f97a1211e232e3f892dfb68f20041d088345d383fffd417f9c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf3b73a22b0de0f97a1211e232e3f892dfb68f20041d088345d383fffd417f9c?s=96&d=mm&r=g\",\"caption\":\"J\"},\"url\":\"https:\\\/\\\/colombiamyway.com\\\/de\\\/author\\\/divisitescuracao\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Von einem Engel in Santa Rosa de Cabal gerettet - Colombia My Way","description":"Medizinische Versorgung in Kolumbien? Hier k\u00f6nnen Sie \u00fcber unsere eigenen Erfahrungen mit einem \"Hausbesuch\" bei den \u00c4rzten von Angeles al Llamado aus Pereira lesen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/colombiamyway.com\/de\/von-einem-engel-in-santa-rosa-de-cabal-gerettet\/","og_locale":"de_DE","og_type":"article","og_title":"Von einem Engel in Santa Rosa de Cabal gerettet - Colombia My Way","og_description":"Medizinische Versorgung in Kolumbien? Hier k\u00f6nnen Sie \u00fcber unsere eigenen Erfahrungen mit einem \"Hausbesuch\" bei den \u00c4rzten von Angeles al Llamado aus Pereira lesen.","og_url":"https:\/\/colombiamyway.com\/de\/von-einem-engel-in-santa-rosa-de-cabal-gerettet\/","og_site_name":"Colombia My Way","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61571407164514","article_published_time":"2020-07-08T22:06:25+00:00","article_modified_time":"2025-09-06T19:25:38+00:00","og_image":[{"width":960,"height":540,"url":"https:\/\/colombiamyway.com\/wp-content\/uploads\/2020\/09\/Angeles-al-Llamado_Pereira_Colombia-copy.jpg","type":"image\/jpeg"}],"author":"J","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"J","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/colombiamyway.com\/de\/von-einem-engel-in-santa-rosa-de-cabal-gerettet\/#article","isPartOf":{"@id":"https:\/\/colombiamyway.com\/de\/von-einem-engel-in-santa-rosa-de-cabal-gerettet\/"},"author":{"name":"J","@id":"https:\/\/colombiamyway.com\/de\/#\/schema\/person\/011d515d7815ef4a06a1d4f782f06711"},"headline":"Von einem Engel in Santa Rosa de Cabal gerettet","datePublished":"2020-07-08T22:06:25+00:00","dateModified":"2025-09-06T19:25:38+00:00","mainEntityOfPage":{"@id":"https:\/\/colombiamyway.com\/de\/von-einem-engel-in-santa-rosa-de-cabal-gerettet\/"},"wordCount":1214,"publisher":{"@id":"https:\/\/colombiamyway.com\/de\/#organization"},"image":{"@id":"https:\/\/colombiamyway.com\/de\/von-einem-engel-in-santa-rosa-de-cabal-gerettet\/#primaryimage"},"thumbnailUrl":"https:\/\/colombiamyway.com\/wp-content\/uploads\/2020\/09\/Angeles-al-Llamado_Pereira_Colombia-copy.jpg","articleSection":["Reiseberichte","Reisef\u00fchrer f\u00fcr das kolumbianische Kaffeedreieck"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/colombiamyway.com\/de\/von-einem-engel-in-santa-rosa-de-cabal-gerettet\/","url":"https:\/\/colombiamyway.com\/de\/von-einem-engel-in-santa-rosa-de-cabal-gerettet\/","name":"Von einem Engel in Santa Rosa de Cabal gerettet - Colombia My Way","isPartOf":{"@id":"https:\/\/colombiamyway.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/colombiamyway.com\/de\/von-einem-engel-in-santa-rosa-de-cabal-gerettet\/#primaryimage"},"image":{"@id":"https:\/\/colombiamyway.com\/de\/von-einem-engel-in-santa-rosa-de-cabal-gerettet\/#primaryimage"},"thumbnailUrl":"https:\/\/colombiamyway.com\/wp-content\/uploads\/2020\/09\/Angeles-al-Llamado_Pereira_Colombia-copy.jpg","datePublished":"2020-07-08T22:06:25+00:00","dateModified":"2025-09-06T19:25:38+00:00","description":"Medizinische Versorgung in Kolumbien? Hier k\u00f6nnen Sie \u00fcber unsere eigenen Erfahrungen mit einem \"Hausbesuch\" bei den \u00c4rzten von Angeles al Llamado aus Pereira lesen.","breadcrumb":{"@id":"https:\/\/colombiamyway.com\/de\/von-einem-engel-in-santa-rosa-de-cabal-gerettet\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/colombiamyway.com\/de\/von-einem-engel-in-santa-rosa-de-cabal-gerettet\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/colombiamyway.com\/de\/von-einem-engel-in-santa-rosa-de-cabal-gerettet\/#primaryimage","url":"https:\/\/colombiamyway.com\/wp-content\/uploads\/2020\/09\/Angeles-al-Llamado_Pereira_Colombia-copy.jpg","contentUrl":"https:\/\/colombiamyway.com\/wp-content\/uploads\/2020\/09\/Angeles-al-Llamado_Pereira_Colombia-copy.jpg","width":960,"height":540},{"@type":"BreadcrumbList","@id":"https:\/\/colombiamyway.com\/de\/von-einem-engel-in-santa-rosa-de-cabal-gerettet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/colombiamyway.com\/de\/startseite\/"},{"@type":"ListItem","position":2,"name":"Von einem Engel in Santa Rosa de Cabal gerettet"}]},{"@type":"WebSite","@id":"https:\/\/colombiamyway.com\/de\/#website","url":"https:\/\/colombiamyway.com\/de\/","name":"Colombia My Way","description":"The Guide for the Independent Traveler","publisher":{"@id":"https:\/\/colombiamyway.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/colombiamyway.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/colombiamyway.com\/de\/#organization","name":"Colombia My Way","url":"https:\/\/colombiamyway.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/colombiamyway.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/colombiamyway.com\/wp-content\/uploads\/2024\/12\/Green-Modern-and-Minimalistic-Travel-Typography-Logo-2.png?fit=500%2C500&ssl=1","contentUrl":"https:\/\/i0.wp.com\/colombiamyway.com\/wp-content\/uploads\/2024\/12\/Green-Modern-and-Minimalistic-Travel-Typography-Logo-2.png?fit=500%2C500&ssl=1","width":500,"height":500,"caption":"Colombia My Way"},"image":{"@id":"https:\/\/colombiamyway.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61571407164514"]},{"@type":"Person","@id":"https:\/\/colombiamyway.com\/de\/#\/schema\/person\/011d515d7815ef4a06a1d4f782f06711","name":"J","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/bf3b73a22b0de0f97a1211e232e3f892dfb68f20041d088345d383fffd417f9c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bf3b73a22b0de0f97a1211e232e3f892dfb68f20041d088345d383fffd417f9c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bf3b73a22b0de0f97a1211e232e3f892dfb68f20041d088345d383fffd417f9c?s=96&d=mm&r=g","caption":"J"},"url":"https:\/\/colombiamyway.com\/de\/author\/divisitescuracao\/"}]}},"_links":{"self":[{"href":"https:\/\/colombiamyway.com\/de\/wp-json\/wp\/v2\/posts\/262470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/colombiamyway.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/colombiamyway.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/colombiamyway.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/colombiamyway.com\/de\/wp-json\/wp\/v2\/comments?post=262470"}],"version-history":[{"count":17,"href":"https:\/\/colombiamyway.com\/de\/wp-json\/wp\/v2\/posts\/262470\/revisions"}],"predecessor-version":[{"id":269391,"href":"https:\/\/colombiamyway.com\/de\/wp-json\/wp\/v2\/posts\/262470\/revisions\/269391"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/colombiamyway.com\/de\/wp-json\/wp\/v2\/media\/259161"}],"wp:attachment":[{"href":"https:\/\/colombiamyway.com\/de\/wp-json\/wp\/v2\/media?parent=262470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/colombiamyway.com\/de\/wp-json\/wp\/v2\/categories?post=262470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/colombiamyway.com\/de\/wp-json\/wp\/v2\/tags?post=262470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}